{"id":12938,"date":"2014-11-07T07:03:54","date_gmt":"2014-11-07T06:03:54","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/artarium\/?p=12938"},"modified":"2014-11-09T19:50:11","modified_gmt":"2014-11-09T18:50:11","slug":"kehricht-pfeift-verliebt-ein-rattenchor","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/artarium\/2014\/11\/07\/kehricht-pfeift-verliebt-ein-rattenchor\/","title":{"rendered":"Am Kehricht pfeift verliebt ein Rattenchor"},"content":{"rendered":"<p><strong>&gt; Sendung: <a href=\"http:\/\/cba.fro.at\/273174\">Artarium vom Sonntag, 9. November<\/a><\/strong> &#8211; <strong>Zum 100. Todestag<\/strong> von <a href=\"http:\/\/www.georgtrakl.de\/index.html\"><strong>Georg Trakl<\/strong><\/a> suchen wir heuer <strong>ein letztes Mal<\/strong> die Schlachtfelder des Ersten Weltkriegs auf. Denn wir verstehen<strong> jenen verzweifelten<\/strong> <strong>Freitod des Salzburger Extremlyrikers<\/strong> am <strong>3. November 1914<\/strong> durchaus als eine direkte Auswirkung der schrecklichen Ereignisse, die er im September selbigen Jahres <strong>als hilfloser Helfer<\/strong> inmitten von todwund zerfetzten Soldaten erlebte, erlitt &#8211; und schlie\u00dflich auch nicht mehr ertrug. Ob dieser d\u00fcnnh\u00e4utige, dauerdepressive und schon seit fr\u00fcher Jugend schwer drogens\u00fcchtige Mensch allerdings von vorn herein zum Scheitern an sich selbst und unter allen Umst\u00e4nden zum Untergang <strong>verurteilt<\/strong> war &#8211; diese Frage <strong>muss offen bleiben<\/strong>. Dass seine <strong>d\u00fcstere Dichtung<\/strong> einen aber auch zur Wahrnehmung unterdr\u00fcckter Emotionen <strong>verf\u00fchren<\/strong> &#8211; und im besten Fall zu deren sprachlichem Ausdruck <strong>bef\u00e4higen<\/strong> kann &#8211; das <strong>darf als gesichert gelten<\/strong>&#8230;<\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/P1010023.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12952\" src=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/P1010023-225x300.jpg\" alt=\"Traklgedenken\" width=\"225\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/P1010023-225x300.jpg 225w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/P1010023-768x1024.jpg 768w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/P1010023.jpg 1536w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><strong>Trakls Wortwelt<\/strong> entzieht sich weitestgehend eindeutiger Interpretation und klarer Zuordnung, wohl auch weil <strong>seine Person<\/strong> dabei stets eine geheimnisvolle geblieben ist. Die Symbole und Stimmungen in seinem Werk erschlie\u00dfen sich immer nur <strong>individuell<\/strong>, <strong>subjektiv<\/strong>. Das jedoch heftig, wie es wohl auch die Zust\u00e4nde waren, in denen sie entstanden sind. Manche(n) mag dies <strong>befremden oder gar verst\u00f6ren<\/strong> &#8211; die eigene Vorstellungskraft wird dabei jedenfalls zwingend in Gang gesetzt. Und so entfaltet sich eine ganz \u00e4hnliche Wirkung wie in der surrealen Malerei, der psychedelischen Musik oder <strong>beim Verzehr von bewusstseinsver\u00e4ndernden<\/strong> &#8230;&#8230; Das \u00fcberlassen wir aber jetzt eurer Phantasie! \ud83d\ude00<\/p>\n<p style=\"text-align: left\"><em>Geduckte H\u00fctten, Pfade wirr verstreut, <\/em><br \/>\n<em> In G\u00e4rten Durcheinander und Bewegung, <\/em><br \/>\n<em> Bisweilen schwillt Geheul aus dumpfer Regung, <\/em><br \/>\n<em> In einer Kinderschar fliegt rot ein Kleid.<\/em><\/p>\n<p style=\"text-align: left\"><em>Am Kehricht pfeift verliebt ein Rattenchor. <\/em><br \/>\n<em> In K\u00f6rben tragen Frauen Eingeweide, <\/em><br \/>\n<em> Ein ekelhafter Zug voll Schmutz und R\u00e4ude, <\/em><br \/>\n<em> Kommen sie aus der D\u00e4mmerung hervor.<\/em><\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/Trakl-Vorstadt-043.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12966\" src=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/Trakl-Vorstadt-043-224x300.jpg\" alt=\"Vorstadt im F\u00f6hn\" width=\"224\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/Trakl-Vorstadt-043-224x300.jpg 224w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/Trakl-Vorstadt-043-768x1024.jpg 768w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2014\/11\/Trakl-Vorstadt-043.jpg 1704w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/a>An einigen Pl\u00e4tzen in der Stadt Salzburg sind <a href=\"http:\/\/kulturerleben.salzburgresearch.at\/poi_kat\/trakl\/\"><strong>Gedichte von Georg Trakl<\/strong><\/a> in der Gestalt von Steintafeln angebracht, so wie das hier zitierte <strong>&#8222;Vorstadt im F\u00f6hn&#8220;<\/strong> neben dem Fernheizwerk bei der Lehener Br\u00fccke, wo sich einstmals der st\u00e4dtische Schlachthof befand. Doch weshalb w\u00fcrdigt man ausgerechnet in dieser <strong>Hochburg angepassten Funktionierens<\/strong> einen Dichter, dem jedwede fr\u00f6hlich geschw\u00e4tzige Normalit\u00e4t zutiefst zuwider war? Sind seine prophetischen Gesichte <strong>vor die S\u00e4ue geworfene Perlen<\/strong>, der Allgemeinheit halt in die Sicht geschraubt, <strong>damit selbst der Umweg<\/strong> kunstsinniger Genie\u00dfer und Individualtouristen <strong>noch rentabel ist?<\/strong> Bizarr&#8230;<\/p>\n<p>Trakls im Spiegel seiner Seele bis zur eigenen Vernichtung verk\u00f6rperten <strong>Vorhaltungen an eine ihn abweisende Spie\u00dfgesellschaft<\/strong> sind hier prominent platziert nachzuvollziehen. Dass <strong>dieses<\/strong> von der eigenen Bedeutung <strong>bis zum Anschlag besoffene Wichtigtum<\/strong>, das menschlich nicht mehr imstande war, auch nur einen einzigen Au\u00dfenseiter aufzunehmen, kurz darauf <strong>halb Europa mit Krieg \u00fcberzog und in Schutt und Asche legte<\/strong>, das sollte uns gerade heute wieder zu denken geben! <strong>Das Unaussprechbare<\/strong>, das Trakl allerdings verklausuliert aufschrieb, <strong>bedarf n\u00e4mlich einer Antwort an den Lebenden<\/strong>, soll es ihn nicht auf Dauer kr\u00e4nken, isolieren &#8211; und schlie\u00dflich umbringen. <strong>Ob Dichtung in der Depression zum Ausweg wird &#8211; oder zum Untergang &#8211; das liegt schon am Du.<\/strong><\/p>\n<p><strong>&gt; Erfrischend Unbl\u00f6des<\/strong> zu Trakls Biographie in diesem <a href=\"http:\/\/www.spiegel.de\/spiegel\/print\/d-41758246.html\"><strong>SPIEGEL Artikel von 1957<\/strong><\/a> \ud83d\ude09<\/p>\n<p><strong>&gt; Lyrik f\u00fcr alle<\/strong> von <strong>Lutz G\u00f6rner<\/strong> (sehr empfehlenswert!) &#8211; <a href=\"http:\/\/www.youtube.com\/watch?v=Zd9Wj8oejzE\"><strong>Georg Trakl (Video)<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt; Sendung: Artarium vom Sonntag, 9. November &#8211; Zum 100. Todestag von Georg Trakl suchen wir heuer ein letztes Mal die Schlachtfelder des Ersten Weltkriegs auf. Denn wir verstehen jenen verzweifelten Freitod des Salzburger Extremlyrikers am 3. November 1914 durchaus &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/artarium\/2014\/11\/07\/kehricht-pfeift-verliebt-ein-rattenchor\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67,69,15],"tags":[91,89,4008,7591],"class_list":["post-12938","post","type-post","status-publish","format-standard","hentry","category-konzept-entwicklung","category-neue-projekte","category-sendungen","tag-die-ursache","tag-portrait","tag-textase","tag-zeit-geschichte"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts\/12938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/comments?post=12938"}],"version-history":[{"count":0,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts\/12938\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/media?parent=12938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/categories?post=12938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/tags?post=12938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}