{"id":14763,"date":"2015-10-09T01:30:30","date_gmt":"2015-10-09T00:30:30","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/artarium\/?p=14763"},"modified":"2015-10-11T19:08:11","modified_gmt":"2015-10-11T18:08:11","slug":"die-kleingeldprinzessin","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/","title":{"rendered":"Die Kleingeldprinzessin"},"content":{"rendered":"<p><strong>&gt; Sendung: <a href=\"http:\/\/cba.fro.at\/298537\">Artarium vom Sonntag, 11. Oktober<\/a><\/strong> &#8211; Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, <strong>im Duett mit Max Prosa<\/strong> &#8211; die <strong>Zuschreibungen<\/strong> sind so mannigfach wie <strong>die Zwischent\u00f6ne<\/strong> dieser sehr speziellen K\u00fcnstlerin, die <strong>mal solo<\/strong>, <strong>mal mit Band<\/strong> unterwegs ist. Nach ihrem Kurznamen <a href=\"http:\/\/www.kleingeldprinzessin.de\/\"><strong>DOTA<\/strong><\/a> hei\u00dft inzwischen auch <a href=\"https:\/\/de.wikipedia.org\/wiki\/Dota_%28Band%29\"><strong>das Gesamtprojekt<\/strong><\/a> so &#8211; und pr\u00e4sentiert sich vermittels einer erfreulich aufger\u00e4umten <a href=\"http:\/\/www.kleingeldprinzessin.de\/\"><strong>Homepage<\/strong><\/a>. Von <a href=\"https:\/\/de.wikipedia.org\/wiki\/Dota_Kehr\"><strong>Dota Kehr<\/strong><\/a> ist hier nat\u00fcrlich die Rede, auch bekannt als <strong>Die Kleingeldprinzessin<\/strong> mit oder ohne <strong>Die Stadtpiraten<\/strong>. Wir spielen im Rahmen unserer Reihe <a href=\"https:\/\/blog.radiofabrik.at\/artarium\/tag\/das-ganze-album\/\"><strong>Das ganze Album<\/strong><\/a> diesmal <strong>ihre CD<\/strong> <a href=\"http:\/\/www.discogs.com\/Dota-Und-Die-Stadtpiraten-Immer-Nur-Rosinen\/release\/2422375\"><strong>&#8222;Immer nur Rosinen&#8220;<\/strong><\/a>, die uns im Ganzen als <strong>&#8222;die Rundeste&#8220;<\/strong> &#8211; und vor allem <strong>textlich wesentlich<\/strong> erscheint. Aber ich lass jetzt lieber mal den <strong>Fachmann f\u00fcrs &#8222;Eindr\u00fccke vermitteln&#8220;<\/strong> ans Werk gehn:<\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/immer-nur-rosinen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14772\" src=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/immer-nur-rosinen-300x300.jpg\" alt=\"immer nur rosinen\" width=\"300\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/immer-nur-rosinen-300x300.jpg 300w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/immer-nur-rosinen-150x150.jpg 150w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/immer-nur-rosinen-1024x1024.jpg 1024w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/immer-nur-rosinen.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><strong>Endlich!<\/strong>, rufe ich in die Nacht hinaus, in <strong>diese regentr\u00e4ge Nacht<\/strong>, und r\u00e4ume das Zimmer leer um Platz zu schaffen f\u00fcr die tausend Dinge, die ich schreiben m\u00f6chte \u00fcber <strong>dieses Album<\/strong>, welches schon viel zu lange <strong>auf der Vielleichtbank<\/strong>, <strong>der Irgendwanneinmalbank<\/strong> sitzt und der Gespieltwerdung harrt. Ich h\u00f6re <strong>Dota Kehr<\/strong>, der Kleingeldprinzessin und ihren Stadtpiraten schon Jahre zu, ob es <em>In anderen R\u00e4umen Blech + Plastik<\/em> oder <em>Immer nur Rosinen<\/em> gibt, die <strong>jazzigen Klanggalaxien<\/strong> mit Bossa Nova und Klezmer-Einfl\u00fcssen, umschlie\u00dfen <strong>mein H\u00f6rleben<\/strong> und zeigen immer wieder <strong>wie lebendig<\/strong>, <strong>wie lebhaft<\/strong> Liedermachen sein kann. Und wie so oft sind es <strong>die Texte<\/strong>, die mich von Anfang an aufhorchen lie\u00dfen; die <strong>feinf\u00fchligen Beobachtungen<\/strong>, die <strong>zeitkritisch ziselierten Zusammenh\u00e4nge<\/strong> in den <strong>vielschichtigen Geschichten<\/strong>, die <strong>umwerfende Umw\u00e4lzung<\/strong> <strong>allt\u00e4glicher Wahrnehmungen<\/strong>, <strong>die Poesie fl\u00fcchtiger Augenblicke<\/strong>, <strong>die Worte &#8211; hinter dem Sinn<\/strong>.<\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/dota.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-14781\" src=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/dota-300x200.jpg\" alt=\"dota\" width=\"300\" height=\"200\" srcset=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/dota-300x200.jpg 300w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/dota-1024x683.jpg 1024w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/dota-450x300.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ich warte hier, und mein Schreibtisch, Zeittisch, blo\u00df von einer Wandlampe erhellt, so dass er <strong>zu meinem Mittelpunkt<\/strong> wird, meinem einzigen <strong>Bezugspunkt<\/strong> im grenzenlosen Schwarz, und ich h\u00f6re <strong>Dotas Stimme<\/strong>, diese freundliche, einladende Stimme, folge der Musik, wohin auch immer; nach <strong>Berlin<\/strong>, in die <strong>Erdumlaufbahn<\/strong>, <strong>hinter die Lider<\/strong>, durchs <strong>Schlaraffenland<\/strong>. F\u00fcr Proviant ist gesorgt, f\u00fcr Gespr\u00e4chsthemen und Konversationsfunken sowieso, meine <strong>Siebenmeilenstiefel<\/strong> tragen mich weiter als gedacht; eine Motte wirft ihre Schatten auf die Tastatur, von drau\u00dfen kein Ger\u00e4usch, hier drinnen nur <strong>das Klimpern<\/strong> meiner Finger, nur mein <strong>stetes Flattern<\/strong> beim Formulieren, das Ann\u00e4hern, Andeuten, <strong>Skizzieren einer ganz eigenen Welt<\/strong>, <strong>die vertrauter nicht sein k\u00f6nnte<\/strong>.<\/p>\n<p>Am Ende bleibt nur zu sagen: <strong>H\u00f6ret selbst<\/strong> und begebt euch mit uns auf <strong>eine Reise in die Zwischent\u00f6ne<\/strong>, <strong>Zwischenzeilen<\/strong> und <strong>Zwischenschluchten<\/strong> dieser <strong>facettenreichen<\/strong>, <strong>phantasievollen<\/strong>, <strong>verbindungsstiftenden &#8211; immer unvollendeten Symphonie<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt; Sendung: Artarium vom Sonntag, 11. Oktober &#8211; Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa &#8211; die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,1,15],"tags":[4009,83,16284,81],"class_list":["post-14763","post","type-post","status-publish","format-standard","hentry","category-artarium-news","category-uncategorized","category-sendungen","tag-das-ganze-album","tag-inteam","tag-musik","tag-review"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&gt; Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\u00dft inzwischen auch das Gesamtprojekt so -\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"artarium\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Artarium - Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Die Kleingeldprinzessin - Artarium\" \/>\n\t\t<meta property=\"og:description\" content=\"&gt; Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\u00dft inzwischen auch das Gesamtprojekt so -\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-10-09T00:30:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-10-11T18:08:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Die Kleingeldprinzessin - Artarium\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&gt; Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\u00dft inzwischen auch das Gesamtprojekt so -\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#blogposting\",\"name\":\"Die Kleingeldprinzessin - Artarium\",\"headline\":\"Die Kleingeldprinzessin\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/files\\\/2015\\\/10\\\/immer-nur-rosinen.jpg\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#articleImage\",\"width\":1280,\"height\":1280},\"datePublished\":\"2015-10-09T01:30:30+01:00\",\"dateModified\":\"2015-10-11T19:08:11+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#webpage\"},\"articleSection\":\"News, Passt in keine Schachtel, Sendung, Das ganze Album!, inteam, Musik, ReView\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Passt in keine Schachtel\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#listItem\",\"name\":\"Die Kleingeldprinzessin\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#listItem\",\"position\":3,\"name\":\"Die Kleingeldprinzessin\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#organization\",\"name\":\"Artarium\",\"description\":\"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/\",\"name\":\"artarium\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=identicon&r=pg\",\"width\":96,\"height\":96,\"caption\":\"artarium\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/\",\"name\":\"Die Kleingeldprinzessin - Artarium\",\"description\":\"> Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\\u00f6ne dieser sehr speziellen K\\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\\u00dft inzwischen auch das Gesamtprojekt so -\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2015\\\/10\\\/09\\\/die-kleingeldprinzessin\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\"},\"datePublished\":\"2015-10-09T01:30:30+01:00\",\"dateModified\":\"2015-10-11T19:08:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/\",\"name\":\"Artarium\",\"description\":\"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Die Kleingeldprinzessin - Artarium","description":"> Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\u00dft inzwischen auch das Gesamtprojekt so -","canonical_url":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#blogposting","name":"Die Kleingeldprinzessin - Artarium","headline":"Die Kleingeldprinzessin","author":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author"},"publisher":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.radiofabrik.at\/artarium\/files\/2015\/10\/immer-nur-rosinen.jpg","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#articleImage","width":1280,"height":1280},"datePublished":"2015-10-09T01:30:30+01:00","dateModified":"2015-10-11T19:08:11+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#webpage"},"articleSection":"News, Passt in keine Schachtel, Sendung, Das ganze Album!, inteam, Musik, ReView"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium#listItem","position":1,"name":"Home","item":"https:\/\/blog.radiofabrik.at\/artarium","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/#listItem","position":2,"name":"Passt in keine Schachtel","item":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#listItem","name":"Die Kleingeldprinzessin"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#listItem","position":3,"name":"Die Kleingeldprinzessin","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}}]},{"@type":"Organization","@id":"https:\/\/blog.radiofabrik.at\/artarium\/#organization","name":"Artarium","description":"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel","url":"https:\/\/blog.radiofabrik.at\/artarium\/"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author","url":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/","name":"artarium","image":{"@type":"ImageObject","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=identicon&r=pg","width":96,"height":96,"caption":"artarium"}},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#webpage","url":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/","name":"Die Kleingeldprinzessin - Artarium","description":"> Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\u00dft inzwischen auch das Gesamtprojekt so -","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/#website"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author"},"creator":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author"},"datePublished":"2015-10-09T01:30:30+01:00","dateModified":"2015-10-11T19:08:11+01:00"},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/artarium\/#website","url":"https:\/\/blog.radiofabrik.at\/artarium\/","name":"Artarium","description":"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Artarium - Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel","og:type":"article","og:title":"Die Kleingeldprinzessin - Artarium","og:description":"&gt; Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\u00dft inzwischen auch das Gesamtprojekt so -","og:url":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/","article:published_time":"2015-10-09T00:30:30+00:00","article:modified_time":"2015-10-11T18:08:11+00:00","twitter:card":"summary","twitter:title":"Die Kleingeldprinzessin - Artarium","twitter:description":"&gt; Sendung: Artarium vom Sonntag, 11. Oktober - Politisch, kritisch, Jazz, Folk, Klezmer, Liedermacherin, geile Texte, eigenes Label, im Duett mit Max Prosa - die Zuschreibungen sind so mannigfach wie die Zwischent\u00f6ne dieser sehr speziellen K\u00fcnstlerin, die mal solo, mal mit Band unterwegs ist. Nach ihrem Kurznamen DOTA hei\u00dft inzwischen auch das Gesamtprojekt so -"},"aioseo_meta_data":{"post_id":"14763","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-09 21:14:20","updated":"2025-06-04 03:51:32","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/artarium\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/\" title=\"Passt in keine Schachtel\">Passt in keine Schachtel<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDie Kleingeldprinzessin\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.radiofabrik.at\/artarium"},{"label":"Passt in keine Schachtel","link":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/"},{"label":"Die Kleingeldprinzessin","link":"https:\/\/blog.radiofabrik.at\/artarium\/2015\/10\/09\/die-kleingeldprinzessin\/"}],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts\/14763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/comments?post=14763"}],"version-history":[{"count":0,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts\/14763\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/media?parent=14763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/categories?post=14763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/tags?post=14763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}