{"id":23942,"date":"2023-03-22T15:17:07","date_gmt":"2023-03-22T14:17:07","guid":{"rendered":"https:\/\/blog.radiofabrik.at\/artarium\/?p=23942"},"modified":"2023-03-26T18:32:43","modified_gmt":"2023-03-26T17:32:43","slug":"es-gibt-kein-richtiges-leben-im-falschen","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/","title":{"rendered":"Es gibt kein richtiges Leben im falschen"},"content":{"rendered":"<p><strong>&gt; Sendung: <a href=\"https:\/\/cba.fro.at\/614218\" target=\"_blank\" rel=\"noopener\">Artarium vom Sonntag, 26. M\u00e4rz<\/a><\/strong> &#8211; <em><strong>\u201cAdorno? A<\/strong><strong>uf den berufen sich viele.\u201d<\/strong><\/em> So h\u00f6rt es sich oft an, wenn <strong>die Geschichte<\/strong> an einem (oder einer anderen) vorbeifliegt und <strong>ihre Schwingen<\/strong> einen pl\u00f6tzlich anr\u00fchren. <strong>Komm<\/strong>, <strong>schwarzer Vogel<\/strong>. <strong>Oder doch ein Engel erl\u00f6sender Erkenntnis?<\/strong> Die Sehnsucht nach dem <strong>m\u00f6glichen Gl\u00fcck<\/strong>, dessen Erinnerung <strong>unter all dem Ger\u00fcmpel<\/strong> unserer <strong>entgleisten<\/strong>, <strong>verbeulten<\/strong> und <strong>besch\u00e4digten Liebe<\/strong> wahrzunehmen w\u00e4re, wenn wir uns nur <strong>selbst ins Gesicht schauen<\/strong> k\u00f6nnten, <strong>ohne die Angst<\/strong>, <strong>am eigenen Spiegelbild zu zerbrechen<\/strong>. Haben wir uns nicht immer wieder einmal <a href=\"https:\/\/blog.radiofabrik.at\/artarium\/2021\/07\/21\/dark-side-of-the-river\/\" target=\"_blank\" rel=\"noopener\"><strong>zwischen Lebensmut und Todeslust befunden?<\/strong><\/a> <strong>Was kommt von au\u00dfen &#8211; und was von innen?<\/strong> <strong>Und wer zur H\u00f6lle spricht da? Wer<\/strong>,<strong> wenn nicht ich<\/strong><strong>? Himmelhoch jauchzend &#8211; <em>dabei zugleich<\/em> <em>zum Leben betr\u00fcbt <\/em><\/strong>&#8230;<\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-23947\" src=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen-300x225.jpg\" alt=\"Es gibt kein richtiges Leben im falschen\" width=\"300\" height=\"225\" srcset=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen-300x225.jpg 300w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen-1024x768.jpg 1024w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen-768x576.jpg 768w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen-1536x1152.jpg 1536w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen-2048x1536.jpg 2048w, https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen-400x300.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Eine angejahrte Dokumentation aus der <strong>kulturellen Treibgutsammlung unserer Individualit\u00e4tsinsel<\/strong> sollte dabei helfen, <strong>den un\u00fcberbr\u00fcckbar scheinenden Selbstwiderspruch<\/strong> in der <strong>radikalen Denkwelt<\/strong> aufzul\u00f6sen:<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=OMrtcGBFdMA\" target=\"_blank\" rel=\"noopener\"><strong>\u201cEs gibt kein richtiges Leben im falschen\u201d<\/strong><\/a><\/p>\n<p>Und es gibt einen <strong>Zusammenhang<\/strong> zwischen diesem <strong>Fehlen von Liebe<\/strong> und unserem <strong>Wissen um ihr Dasein<\/strong>. Eine Spur, die uns der wirklich kluge <a href=\"https:\/\/de.wikipedia.org\/wiki\/Alexander_Kluge\" target=\"_blank\" rel=\"noopener\"><strong>Alexander Kluge<\/strong><\/a> legt, indem er einf\u00fchlsam und verst\u00e4ndig <strong>Adornos Lebensgeschichte<\/strong> mit der uns alle <strong>umgebenden Weltgeschichte<\/strong> <em>(\u201ces ist falsch gelaufen\u201d)<\/em> verkn\u00fcpft. <strong>Eine Spur<\/strong>, die wir <strong>als roten Faden<\/strong> zum <strong>Verstehen unserer Gegenwart<\/strong> im Spiegel von <strong>Adornos<\/strong> <strong>weit \u00fcber seine Zeit hinaus wirksamem Denken<\/strong> aufnehmen &#8211; und darstellen wollen. Und wenn es <strong>ein gl\u00fcckhaftes Zusammentreffen mehrerer quasi als Flaschenpost<\/strong> <strong>\u00fcberlieferter Wahrheiten<\/strong> gibt &#8211; <strong>was ist eigentlich die Mehrzahl von Flaschenpost?<\/strong><\/p>\n<p>Ich bin oft <strong>ziemlich zerrissen<\/strong> zwischen <strong>meiner Vorstellung vom \u201crichtigen Leben\u201d<\/strong> und dem, <strong>womit mich <em>die Realit\u00e4ter*innen<\/em> in meiner Erfahrung konfrontieren<\/strong>. Ein Zustand, der mich immer wieder <strong>krank<\/strong> und <strong>ungl\u00fccklich<\/strong> macht. <strong>Nichtsdestoweniger<\/strong> suche ich unentwegt (oder \u201csucht es in mir\u201d?) <strong>nach einer sinnvollen Verbindung mit dem<\/strong>, <strong>was da gewesen sein muss<\/strong>, <strong>bevor <em>\u201ces falsch gelaufen ist\u201d<\/em><\/strong>. Dabei geriet mir unl\u00e4ngst wieder <strong>\u201cDas Buch von der Liebe\u201d<\/strong> von <a href=\"https:\/\/de.wikipedia.org\/wiki\/Ernesto_Cardenal\" target=\"_blank\" rel=\"noopener\"><strong>Ernesto Cardenal<\/strong><\/a> in die H\u00e4nde und ich las <a href=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Ernesto-Cardenal-Thomas-Merton-Liebe-Vorwort.pdf\" target=\"_blank\" rel=\"noopener\"><strong>das Vorwort von Thomas Merton<\/strong>.<\/a> K\u00f6nnte das vielleicht <strong>eine Erkl\u00e4rung<\/strong> sein?<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=Yzi9B0-MsVs\" target=\"_blank\" rel=\"noopener\"><strong>Eine hei\u00dfe Spur?<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt; Sendung: Artarium vom Sonntag, 26. M\u00e4rz &#8211; \u201cAdorno? Auf den berufen sich viele.\u201d So h\u00f6rt es sich oft an, wenn die Geschichte an einem (oder einer anderen) vorbeifliegt und ihre Schwingen einen pl\u00f6tzlich anr\u00fchren. Komm, schwarzer Vogel. Oder doch &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67,68,1,69,15],"tags":[91,83,84,89,81,4008,7591],"class_list":["post-23942","post","type-post","status-publish","format-standard","hentry","category-konzept-entwicklung","category-artarium-news","category-uncategorized","category-neue-projekte","category-sendungen","tag-die-ursache","tag-inteam","tag-kunnst","tag-portrait","tag-review","tag-textase","tag-zeit-geschichte"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"artarium\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Artarium - Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Es gibt kein richtiges Leben im falschen - Artarium\" \/>\n\t\t<meta property=\"og:description\" content=\"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2272\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-03-22T14:17:07+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-03-26T17:32:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Es gibt kein richtiges Leben im falschen - Artarium\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#blogposting\",\"name\":\"Es gibt kein richtiges Leben im falschen - Artarium\",\"headline\":\"Es gibt kein richtiges Leben im falschen\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/files\\\/2023\\\/03\\\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#articleImage\",\"width\":2272,\"height\":1704,\"caption\":\"Es gibt kein richtiges Leben im falschen\"},\"datePublished\":\"2023-03-22T15:17:07+01:00\",\"dateModified\":\"2023-03-26T18:32:43+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#webpage\"},\"articleSection\":\"Konzept, News, Passt in keine Schachtel, Projekt, Sendung, Die Ursache, inteam, KUNNST?, Portrait, ReView, TEXTASE, Zeit Geschichte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Passt in keine Schachtel\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#listItem\",\"name\":\"Es gibt kein richtiges Leben im falschen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#listItem\",\"position\":3,\"name\":\"Es gibt kein richtiges Leben im falschen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#organization\",\"name\":\"Artarium\",\"description\":\"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/\",\"name\":\"artarium\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=identicon&r=pg\",\"width\":96,\"height\":96,\"caption\":\"artarium\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/\",\"name\":\"Es gibt kein richtiges Leben im falschen - Artarium\",\"description\":\"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \\u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/2023\\\/03\\\/22\\\/es-gibt-kein-richtiges-leben-im-falschen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/author\\\/artarium\\\/#author\"},\"datePublished\":\"2023-03-22T15:17:07+01:00\",\"dateModified\":\"2023-03-26T18:32:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/\",\"name\":\"Artarium\",\"description\":\"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/artarium\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Es gibt kein richtiges Leben im falschen - Artarium","description":"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.","canonical_url":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#blogposting","name":"Es gibt kein richtiges Leben im falschen - Artarium","headline":"Es gibt kein richtiges Leben im falschen","author":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author"},"publisher":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#articleImage","width":2272,"height":1704,"caption":"Es gibt kein richtiges Leben im falschen"},"datePublished":"2023-03-22T15:17:07+01:00","dateModified":"2023-03-26T18:32:43+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#webpage"},"articleSection":"Konzept, News, Passt in keine Schachtel, Projekt, Sendung, Die Ursache, inteam, KUNNST?, Portrait, ReView, TEXTASE, Zeit Geschichte"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium#listItem","position":1,"name":"Home","item":"https:\/\/blog.radiofabrik.at\/artarium","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/#listItem","position":2,"name":"Passt in keine Schachtel","item":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#listItem","name":"Es gibt kein richtiges Leben im falschen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#listItem","position":3,"name":"Es gibt kein richtiges Leben im falschen","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}}]},{"@type":"Organization","@id":"https:\/\/blog.radiofabrik.at\/artarium\/#organization","name":"Artarium","description":"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel","url":"https:\/\/blog.radiofabrik.at\/artarium\/"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author","url":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/","name":"artarium","image":{"@type":"ImageObject","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=identicon&r=pg","width":96,"height":96,"caption":"artarium"}},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#webpage","url":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/","name":"Es gibt kein richtiges Leben im falschen - Artarium","description":"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/#website"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author"},"creator":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/author\/artarium\/#author"},"datePublished":"2023-03-22T15:17:07+01:00","dateModified":"2023-03-26T18:32:43+01:00"},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/artarium\/#website","url":"https:\/\/blog.radiofabrik.at\/artarium\/","name":"Artarium","description":"Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.radiofabrik.at\/artarium\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Artarium - Das etwas andere Kunnst-Biotop im Schatten der Mozartkugel","og:type":"article","og:title":"Es gibt kein richtiges Leben im falschen - Artarium","og:description":"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.","og:url":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/","og:image":"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg","og:image:secure_url":"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg","og:image:width":"2272","og:image:height":"1704","article:published_time":"2023-03-22T14:17:07+00:00","article:modified_time":"2023-03-26T17:32:43+00:00","twitter:card":"summary","twitter:title":"Es gibt kein richtiges Leben im falschen - Artarium","twitter:description":"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.","twitter:image":"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg"},"aioseo_meta_data":{"post_id":"23942","title":null,"description":"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.","keywords":[],"keyphrases":{"focus":{"keyphrase":"Leben","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":"Eine Spur zum Verstehen unserer Gegenwart im Spiegel von Adornos weit \u00fcber seine Zeit hinaus wirksamem Denken: Es gibt kein richtiges Leben im falschen.","og_object_type":"default","og_image_type":"content","og_image_url":"https:\/\/blog.radiofabrik.at\/artarium\/files\/2023\/03\/Es-gibt-kein-richtiges-Leben-im-falschen.jpg","og_image_width":"2272","og_image_height":"1704","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-22 11:54:01","updated":"2025-06-04 04:45:55","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/artarium\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/\" title=\"Passt in keine Schachtel\">Passt in keine Schachtel<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEs gibt kein richtiges Leben im falschen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.radiofabrik.at\/artarium"},{"label":"Passt in keine Schachtel","link":"https:\/\/blog.radiofabrik.at\/artarium\/category\/uncategorized\/"},{"label":"Es gibt kein richtiges Leben im falschen","link":"https:\/\/blog.radiofabrik.at\/artarium\/2023\/03\/22\/es-gibt-kein-richtiges-leben-im-falschen\/"}],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts\/23942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/comments?post=23942"}],"version-history":[{"count":25,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts\/23942\/revisions"}],"predecessor-version":[{"id":23970,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/posts\/23942\/revisions\/23970"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/media?parent=23942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/categories?post=23942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/artarium\/wp-json\/wp\/v2\/tags?post=23942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}