{"id":1031,"date":"2018-11-21T22:12:59","date_gmt":"2018-11-21T22:12:59","guid":{"rendered":"https:\/\/blog.radiofabrik.at\/hunderunde\/?p=1031"},"modified":"2019-11-22T21:51:46","modified_gmt":"2019-11-22T21:51:46","slug":"wissen-statt-gewalt-was-gutes-training-ausmacht","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/","title":{"rendered":"Wissen statt Gewalt \u2013 was gutes Training ausmacht"},"content":{"rendered":"<p>Vanessa hat eine 8j\u00e4hrige Cane Corso H\u00fcndin mit Namen Lotta. Lotta ist im Alter von dreieinhalb Jahren bei Vanessa eingezogen und bald hat sich herausgestellt, dass professionelle Hilfe vonn\u00f6ten ist.\u00a0 Es begann eine Reise durch die deutsche Trainingslandschaft, von der Vanessa in der aktuellen Hunderunde berichtet.\u00a0 4 TrainerInnen waren es insgesamt, mit denen Vanessa und Lotta zusammengearbeitet haben. Anfangs war immer der Profibonus schlagend, weil die ambitionierte Hundehalterin selbstverst\u00e4ndlich davon ausgegangen war, dass die Trainerin ja schlie\u00dflich wissen musste, was sie da tat. Und doch kam immer auch der Moment, in dem das Bauchgef\u00fchl Vanessa dazu bewog, weiterzusuchen.<\/p>\n<blockquote><p><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessa_vKarweg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1033\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessa_vKarweg-147x300.jpg\" alt=\"frau mit hund\" width=\"147\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessa_vKarweg-147x300.jpg 147w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessa_vKarweg.jpg 280w\" sizes=\"auto, (max-width: 147px) 100vw, 147px\" \/><\/a>&#8222;Alle Trainerinnen h\u00e4tten erkennen m\u00fcssen, dass ich von der Rasse keine Ahnung hatte. Und es w\u00e4re gut gewesen, wenn ich durch die Trainer \u00fcber die Art, die Charkatereigenschaften, die Verhaltensweisen etwas mehr gelernt h\u00e4tte.&#8220;<\/p><\/blockquote>\n<p>Vanessa bildete sich auf eigene Faust weiter und lernte vieles \u00fcber Hunde und \u00fcber ihre Lotta. Zu guter Letzt ist sie auch bei einer Trainerin gelandet, bei der sie sich gut aufgehoben f\u00fchlt. Ihre Anspr\u00fcche an Lotta hat sie an die M\u00f6glichkeiten angepasst, ihre Erwartungen dort und da reduziert. Und sie hat gemeinsam mit Lotta einen guten Weg gefunden, der ihnen beiden guttut.<\/p>\n<p>&nbsp;<\/p>\n<h3>Trainerin mit Leib und Seele<\/h3>\n<p>Rosee Riggs ist Inhaberin der Hundeschule Good Dog Practice und bem\u00fcht sich auf vielf\u00e4ltige Weise um ein freundliches Miteinander zwischen Mensch und Tier. Rosee ist geb\u00fcrtige Engl\u00e4nderin und lebt mit ihren Hunden im nieder\u00f6sterreichischen Gloggnitz. Rosee ist Erwachsenenbildnerin in den Bereichen Schauspiel und Ensemblebildung und als Trainerin f\u00fcr Teambildung und F\u00fchrungskompetenzen gefragt. Auch in ihrem Zweitberuf als Hundetrainerin wendet sie sich an die Menschen mindestens ebenso wie an die Hunde.<\/p>\n<p>Abgesehen von fundiertem Wissen brauchen HundetrainerInnen ihrer Meinung nach sehr viel Kreativit\u00e4t, damit Mensch und Hund am Training nicht nur Spa\u00df haben, sondern als Team, das einander vertraut, nach Hause gehen.<\/p>\n<blockquote><p>&#8222;Eine Mensch-Hund Beziehung, die auf gegenseitiges Vertrauen baut, ist ein St\u00fcck Lebensqualit\u00e4t.&#8220;<\/p><\/blockquote>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/Spaziergang-blass-300x300.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1035\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/Spaziergang-blass-300x300.jpg\" alt=\"rosee riggs mit hund\" width=\"300\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/Spaziergang-blass-300x300.jpg 300w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/Spaziergang-blass-300x300-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>F\u00fcr Rosee Riggs ist es wichtig, auch kleine Erfolgserlebnisse zu schaffen und daf\u00fcr zu sorgen, dass Mensch und Hund gemeinsam angenehme Dinge machen und sich nicht st\u00e4ndig unter Druck setzen.<\/p>\n<p>Neben der Arbeit mit ihren KlientInnen leitet Rosee Riggs zusammen mit ihrer Kollegin, Patricia Bisztron, das Ausbildungszentrum ISCP &#8211; Austria, das Seminare und Workshops f\u00fcr Menschen in Hundeberufen und auch f\u00fcr interessierte HundehalterInnen, anbietet.<\/p>\n<p>&nbsp;<\/p>\n<h2>Servicebox<\/h2>\n<p><a href=\"https:\/\/www.facebook.com\/vanessashome\" target=\"_blank\" rel=\"noopener noreferrer\">Vanessa vom Karweg<\/a><br \/>\nRosee Riggs<br \/>\n<a href=\"http:\/\/www.good-dog-practise.eu\" target=\"_blank\" rel=\"noopener noreferrer\">Good Dog Practice<\/a><br \/>\nAusbildungszentrum ISCP &#8211; Austria (<a href=\"https:\/\/theiscp.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">The International School for Canine Psychology and Behaviour Ltd &#8211; ISCP<\/a>)<\/p>\n<p><strong>Modernes Hundetraining:<\/strong><br \/>\n<a href=\"http:\/\/trainieren-statt-dominieren.de\/\">Trainieren statt dominieren<\/a><br \/>\n<a href=\"http:\/\/gewaltfreies-hundetraining.ch\/\" target=\"_blank\" rel=\"noopener noreferrer\">Initiative gewaltfreies Hundetraining<\/a><br \/>\n<a href=\"http:\/\/www.voeht.at\">V\u00d6HT-Vereinigung \u00f6sterreichischer HundetrainerInnen und -verhaltensberaterInnen<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/cba.fro.at\/388762\" target=\"_blank\" rel=\"noopener noreferrer\">Hier geht&#8217;s zur Sendung<\/a><\/p>\n<h2>Lesefutter<\/h2>\n<p>Rosie Lowry,\u00a0 <strong>Die stille Kommunikation der Hunde verstehen<\/strong><br \/>\nUte Blaschke-Berthold, <strong>Das Kleingedruckte in der K\u00f6rpersprache des Hundes<\/strong><br \/>\nDorothee Schneider, <strong>Die Welt in seinem Kopf<\/strong><br \/>\nSuzanne Clothier, <strong>Es w\u00fcrde Knochen vom Himmel regnen<\/strong><br \/>\nJohn Bradshaw, <strong>Hundeverstand<\/strong><br \/>\nKurt Kotrschal, <strong>Einfach beste Freunde, warum Menschen und andere Tiere einander verstehen<\/strong>, <strong>Hund und Mensch, das Geheimnis unserer Seelenverwandtschaft<\/strong><\/p>\n<h3>Musik<\/h3>\n<p>Simon and Garfunkel, Filmmusik aus A dogs purpose<br \/>\nDean Martin und Nat King Cole, Open up the dog house<br \/>\nIlse Werner, Ich m\u00f6chte dein Schiwawa sein<\/p>\n<p>&nbsp;<\/p>\n<h3>Sendung anh\u00f6ren<\/h3>\n<p>Live auf der <a href=\"http:\/\/www.radiofabrik.at\/home.html\">Radiofabrik<\/a> 107,5 oder per <a class=\"broken_link\" href=\"http:\/\/www.radiofabrik.at\/programm0\/sendedaten.html#c5829\" target=\"_blank\" rel=\"noopener noreferrer\">APP<\/a> immer am 2. Mittwoch im Monat um 12:08 Uhr und am 2. Donnerstag im Monat um 19:08 Uhr. Nachh\u00f6ren ebenfalls \u00fcber die <a href=\"http:\/\/www.radiofabrik.at\/programm0\/sendungenvona-z\/hunderunde.html\">Radiofabrik, <\/a>\u00fcber den <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hunderunde Blog <\/a>oder direkt \u00fcber das <a href=\"https:\/\/cba.fro.at\/series\/hunderunde\">Archiv <\/a>.<\/p>\n<p>Feedback und Kontakt: Karin Immler, <a href=\"http:\/\/www.knowwau.com\/\">www.knowwau.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vanessa hat eine 8j\u00e4hrige Cane Corso H\u00fcndin mit Namen Lotta. Lotta ist im Alter von dreieinhalb Jahren bei Vanessa eingezogen und bald hat sich herausgestellt, dass professionelle Hilfe vonn\u00f6ten ist.\u00a0 Es begann eine Reise durch die deutsche Trainingslandschaft, von der Vanessa in der aktuellen Hunderunde berichtet.\u00a0 4 TrainerInnen waren es insgesamt, mit denen Vanessa und &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/\" class=\"more-link\"><span class=\"screen-reader-text\">Wissen statt Gewalt \u2013 was gutes Training ausmacht<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":682,"featured_media":1038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[22827,18385,22995,29824],"class_list":["post-1031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-gewaltfrei","tag-hundeerziehung","tag-positive-verstaerkung","tag-trainer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wissen statt Gewalt \u2013 was gutes Training ausmacht - Hunderunde<\/title>\n<meta name=\"description\" content=\"Woran merkt man eigentlich, dass man bei einem guten Trainer, bei einer guten Trainerin gelandet ist. Und was bedeutet &quot;gut&quot; in dem Zusammenhang?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wissen statt Gewalt \u2013 was gutes Training ausmacht - Hunderunde\" \/>\n<meta property=\"og:description\" content=\"Woran merkt man eigentlich, dass man bei einem guten Trainer, bei einer guten Trainerin gelandet ist. Und was bedeutet &quot;gut&quot; in dem Zusammenhang?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/\" \/>\n<meta property=\"og:site_name\" content=\"Hunderunde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/karin.immler.7\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/knowwau\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-21T22:12:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-22T21:51:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessavomkarweg.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Karin Immler\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karin Immler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/\"},\"author\":{\"name\":\"Karin Immler\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"headline\":\"Wissen statt Gewalt \u2013 was gutes Training ausmacht\",\"datePublished\":\"2018-11-21T22:12:59+00:00\",\"dateModified\":\"2019-11-22T21:51:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/\"},\"wordCount\":590,\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2018\\\/10\\\/cvanessavomkarweg.png\",\"keywords\":[\"gewaltfrei\",\"Hundeerziehung\",\"positive Verst\u00e4rkung\",\"Trainer\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/\",\"name\":\"Wissen statt Gewalt \u2013 was gutes Training ausmacht - Hunderunde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2018\\\/10\\\/cvanessavomkarweg.png\",\"datePublished\":\"2018-11-21T22:12:59+00:00\",\"dateModified\":\"2019-11-22T21:51:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"description\":\"Woran merkt man eigentlich, dass man bei einem guten Trainer, bei einer guten Trainerin gelandet ist. Und was bedeutet \\\"gut\\\" in dem Zusammenhang?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2018\\\/10\\\/cvanessavomkarweg.png\",\"contentUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2018\\\/10\\\/cvanessavomkarweg.png\",\"width\":1200,\"height\":628,\"caption\":\"Lotta vom Karweg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2018\\\/11\\\/21\\\/wissen-statt-gewalt-was-gutes-training-ausmacht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wissen statt Gewalt \u2013 was gutes Training ausmacht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\",\"name\":\"Hunderunde\",\"description\":\"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\",\"name\":\"Karin Immler\",\"sameAs\":[\"http:\\\/\\\/www.knowwau.com\",\"www.facebook.com\\\/knowwau\"],\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/author\\\/hunderunde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wissen statt Gewalt \u2013 was gutes Training ausmacht - Hunderunde","description":"Woran merkt man eigentlich, dass man bei einem guten Trainer, bei einer guten Trainerin gelandet ist. Und was bedeutet \"gut\" in dem Zusammenhang?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/","og_locale":"de_DE","og_type":"article","og_title":"Wissen statt Gewalt \u2013 was gutes Training ausmacht - Hunderunde","og_description":"Woran merkt man eigentlich, dass man bei einem guten Trainer, bei einer guten Trainerin gelandet ist. Und was bedeutet \"gut\" in dem Zusammenhang?","og_url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/","og_site_name":"Hunderunde","article_publisher":"https:\/\/www.facebook.com\/karin.immler.7","article_author":"www.facebook.com\/knowwau","article_published_time":"2018-11-21T22:12:59+00:00","article_modified_time":"2019-11-22T21:51:46+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessavomkarweg.png","type":"image\/png"}],"author":"Karin Immler","twitter_misc":{"Verfasst von":"Karin Immler","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/#article","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/"},"author":{"name":"Karin Immler","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"headline":"Wissen statt Gewalt \u2013 was gutes Training ausmacht","datePublished":"2018-11-21T22:12:59+00:00","dateModified":"2019-11-22T21:51:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/"},"wordCount":590,"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessavomkarweg.png","keywords":["gewaltfrei","Hundeerziehung","positive Verst\u00e4rkung","Trainer"],"articleSection":["Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/","name":"Wissen statt Gewalt \u2013 was gutes Training ausmacht - Hunderunde","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/#primaryimage"},"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessavomkarweg.png","datePublished":"2018-11-21T22:12:59+00:00","dateModified":"2019-11-22T21:51:46+00:00","author":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"description":"Woran merkt man eigentlich, dass man bei einem guten Trainer, bei einer guten Trainerin gelandet ist. Und was bedeutet \"gut\" in dem Zusammenhang?","breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/#primaryimage","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessavomkarweg.png","contentUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2018\/10\/cvanessavomkarweg.png","width":1200,"height":628,"caption":"Lotta vom Karweg"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2018\/11\/21\/wissen-statt-gewalt-was-gutes-training-ausmacht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.radiofabrik.at\/hunderunde\/"},{"@type":"ListItem","position":2,"name":"Wissen statt Gewalt \u2013 was gutes Training ausmacht"}]},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/","name":"Hunderunde","description":"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.radiofabrik.at\/hunderunde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3","name":"Karin Immler","sameAs":["http:\/\/www.knowwau.com","www.facebook.com\/knowwau"],"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/author\/hunderunde\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/1031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/users\/682"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/comments?post=1031"}],"version-history":[{"count":6,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/1031\/revisions"}],"predecessor-version":[{"id":1179,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/1031\/revisions\/1179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/media\/1038"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/media?parent=1031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/categories?post=1031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/tags?post=1031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}