{"id":64,"date":"2014-09-06T21:26:07","date_gmt":"2014-09-06T21:26:07","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/hunderunde\/?p=64"},"modified":"2014-09-06T21:26:07","modified_gmt":"2014-09-06T21:26:07","slug":"war-frueher-alles-besser","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/","title":{"rendered":"War fr\u00fcher alles besser?"},"content":{"rendered":"<h2>War fr\u00fcher das Leben f\u00fcr Hunde besser?<\/h2>\n<p>Oder schlechter? Oder einfach nur anders? Was hat sich im Bezug auf Hundehaltung und Hundeerziehung ver\u00e4ndert? Waren Hunde fr\u00fcher besser erzogen oder hatte man einfach nur ganz andere Erwartungen?<\/p>\n<h2>Unser Umgang mit Hunden&#8230;<\/h2>\n<figure id=\"attachment_77\" aria-describedby=\"caption-attachment-77\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-77 size-medium\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-300x300.jpg\" alt=\"Karin im Studio\" width=\"300\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-300x300.jpg 300w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-150x150.jpg 150w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-77\" class=\"wp-caption-text\">Im Studio der Radiofabrik<\/figcaption><\/figure>\n<p>hat sich in den vergangenen 20 Jahren viel ver\u00e4ndert &#8211; auch wenn manche Zeitgenossen das so gar nicht wahr haben wollen.<\/p>\n<p>\u00dcber Ver\u00e4nderungen in der Herangehensweise, in den Erwartungen an unsere Hunde, \u00fcber Hunde und Menschen plaudere ich in der Sendung mit Mag. Claudia Signitzer-Woral, die seit ihrer Kindheit einen Hund an ihrer Seite hat. Sie erz\u00e4hlt \u00fcber ihre Erfahrungen in der Hundeschule, die sie\u00a0 vor 30 Jahren besucht hat. Und \u00fcber die Erfahrungen, die sie mit ihrer jetzigen H\u00fcndin Kyla, ihrem &#8222;Schulhund&#8220; gemacht hat. War Spazieren gehen mit dem Hund fr\u00fcher einfacher? Ist man \u00fcberhaupt soviel Spazieren gegangen? Und unsere Erwartungen an die <a href=\"http:\/\/www.knowwau.com\" target=\"_blank\">Erziehung <\/a>unserer Hunde, sind die nicht wesentlich h\u00f6her geworden?<\/p>\n<p>H\u00f6ren Sie, was meine Gespr\u00e4chspartner <a title=\"Du musst ihm zeigen, wer der Herr ist\" href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/08\/27\/neues-zur-hundehaltung\/\" target=\"_blank\">Herr Dr. Schmid <\/a>und Frau Mag. Signitzer-Woral zu sagen haben &#8211; wir freuen uns auf Sie!<\/p>\n<p>Nat\u00fcrlich gibt es auch wieder Musik in der Sendung, bei der es ebenfalls um Hunde geht. Mit von der Partie sind diesmal unter anderem Marc Knopfler und Freddie Fender.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>War fr\u00fcher das Leben f\u00fcr Hunde besser? Oder schlechter? Oder einfach nur anders? Was hat sich im Bezug auf Hundehaltung und Hundeerziehung ver\u00e4ndert? Waren Hunde fr\u00fcher besser erzogen oder hatte man einfach nur ganz andere Erwartungen? Unser Umgang mit Hunden&#8230; hat sich in den vergangenen 20 Jahren viel ver\u00e4ndert &#8211; auch wenn manche Zeitgenossen das &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/\" class=\"more-link\"><span class=\"screen-reader-text\">War fr\u00fcher alles besser?<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":682,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[22827,17698,21704,28619,26174,18385,17891,28421,19716],"class_list":["post-64","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-gewaltfrei","tag-hund","tag-hunde","tag-hunde-erziehen","tag-hundeausbildung","tag-hundeerziehung","tag-hundehaltung","tag-hundehaltungsverordnung","tag-hundeschule"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>War fr\u00fcher alles besser? - Hunderunde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"War fr\u00fcher alles besser? - Hunderunde\" \/>\n<meta property=\"og:description\" content=\"War fr\u00fcher das Leben f\u00fcr Hunde besser? Oder schlechter? Oder einfach nur anders? Was hat sich im Bezug auf Hundehaltung und Hundeerziehung ver\u00e4ndert? Waren Hunde fr\u00fcher besser erzogen oder hatte man einfach nur ganz andere Erwartungen? Unser Umgang mit Hunden&#8230; hat sich in den vergangenen 20 Jahren viel ver\u00e4ndert &#8211; auch wenn manche Zeitgenossen das &hellip; War fr\u00fcher alles besser? weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/\" \/>\n<meta property=\"og:site_name\" content=\"Hunderunde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/karin.immler.7\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/knowwau\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-06T21:26:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-300x300.jpg\" \/>\n<meta name=\"author\" content=\"Karin Immler\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karin Immler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/\"},\"author\":{\"name\":\"Karin Immler\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"headline\":\"War fr\u00fcher alles besser?\",\"datePublished\":\"2014-09-06T21:26:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/\"},\"wordCount\":231,\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2014\\\/09\\\/karinstudio-300x300.jpg\",\"keywords\":[\"gewaltfrei\",\"Hund\",\"Hunde\",\"Hunde erziehen\",\"Hundeausbildung\",\"Hundeerziehung\",\"Hundehaltung\",\"Hundehaltungsverordnung\",\"Hundeschule\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/\",\"name\":\"War fr\u00fcher alles besser? - Hunderunde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2014\\\/09\\\/karinstudio-300x300.jpg\",\"datePublished\":\"2014-09-06T21:26:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2014\\\/09\\\/karinstudio.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2014\\\/09\\\/karinstudio.jpg\",\"width\":2646,\"height\":2646,\"caption\":\"Im Studio der Radiofabrik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2014\\\/09\\\/06\\\/war-frueher-alles-besser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"War fr\u00fcher alles besser?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\",\"name\":\"Hunderunde\",\"description\":\"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\",\"name\":\"Karin Immler\",\"sameAs\":[\"http:\\\/\\\/www.knowwau.com\",\"www.facebook.com\\\/knowwau\"],\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/author\\\/hunderunde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"War fr\u00fcher alles besser? - Hunderunde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/","og_locale":"de_DE","og_type":"article","og_title":"War fr\u00fcher alles besser? - Hunderunde","og_description":"War fr\u00fcher das Leben f\u00fcr Hunde besser? Oder schlechter? Oder einfach nur anders? Was hat sich im Bezug auf Hundehaltung und Hundeerziehung ver\u00e4ndert? Waren Hunde fr\u00fcher besser erzogen oder hatte man einfach nur ganz andere Erwartungen? Unser Umgang mit Hunden&#8230; hat sich in den vergangenen 20 Jahren viel ver\u00e4ndert &#8211; auch wenn manche Zeitgenossen das &hellip; War fr\u00fcher alles besser? weiterlesen &rarr;","og_url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/","og_site_name":"Hunderunde","article_publisher":"https:\/\/www.facebook.com\/karin.immler.7","article_author":"www.facebook.com\/knowwau","article_published_time":"2014-09-06T21:26:07+00:00","og_image":[{"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-300x300.jpg","type":"","width":"","height":""}],"author":"Karin Immler","twitter_misc":{"Verfasst von":"Karin Immler","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/#article","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/"},"author":{"name":"Karin Immler","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"headline":"War fr\u00fcher alles besser?","datePublished":"2014-09-06T21:26:07+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/"},"wordCount":231,"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-300x300.jpg","keywords":["gewaltfrei","Hund","Hunde","Hunde erziehen","Hundeausbildung","Hundeerziehung","Hundehaltung","Hundehaltungsverordnung","Hundeschule"],"articleSection":["Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/","name":"War fr\u00fcher alles besser? - Hunderunde","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/#primaryimage"},"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio-300x300.jpg","datePublished":"2014-09-06T21:26:07+00:00","author":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/#primaryimage","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio.jpg","contentUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2014\/09\/karinstudio.jpg","width":2646,"height":2646,"caption":"Im Studio der Radiofabrik"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2014\/09\/06\/war-frueher-alles-besser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.radiofabrik.at\/hunderunde\/"},{"@type":"ListItem","position":2,"name":"War fr\u00fcher alles besser?"}]},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/","name":"Hunderunde","description":"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.radiofabrik.at\/hunderunde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3","name":"Karin Immler","sameAs":["http:\/\/www.knowwau.com","www.facebook.com\/knowwau"],"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/author\/hunderunde\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/users\/682"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":4,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":80,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/64\/revisions\/80"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}