{"id":661,"date":"2016-09-15T20:03:04","date_gmt":"2016-09-15T20:03:04","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/hunderunde\/?p=661"},"modified":"2025-07-01T12:21:46","modified_gmt":"2025-07-01T12:21:46","slug":"beziehungspflege-mit-hunden-sprechen","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/","title":{"rendered":"Beziehungspflege &#8211; mit Hunden sprechen"},"content":{"rendered":"<h4>Menschen, die mit Hunden sprechen<\/h4>\n<p>Immer mehr Menschen w\u00fcnschen sich eine tiefe und innige Beziehung zu ihren Tieren. Das zeigt sich nicht nur im Trend zu gewaltfreien Trainingsmethoden sondern auch in der Bereitschaft, mehr und mehr eine ganzheitliche Sichtweise auf die Mensch-Tier-Beziehung einzunehmen. Die Wissenschaft besch\u00e4ftigt sich derzeit intensiv damit, wie Menschen und Hunde sich austauschen,\u00a0 wie sie miteinander umgehen und sich verst\u00e4ndigen, sowie mit dem Lernverhalten und der Gef\u00fchlswelt unserer Hunde. Schlag auf Schlag werden spannende und vielfach unerwartete Erkenntnisse ver\u00f6ffentlicht.<\/p>\n<blockquote><p>\u201eDie Ethik kann Tiere nicht ausschlie\u00dfen &#8211; nur einschlie\u00dfen!\u201c Elisabeth Berger<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h4>Ethik und spirituelle Anbindung<\/h4>\n<figure id=\"attachment_664\" aria-describedby=\"caption-attachment-664\" style=\"width: 219px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Das-Leben-ist-bunt-24-Aug16.jpg\" target=\"_blank\" rel=\"noopener www.online-mit-tieren.com\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-664 size-medium\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Das-Leben-ist-bunt-24-Aug16-219x300.jpg\" alt=\"Das Leben ist bunt, Elisabeth Berger\" width=\"219\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Das-Leben-ist-bunt-24-Aug16-219x300.jpg 219w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Das-Leben-ist-bunt-24-Aug16.jpg 389w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/a><figcaption id=\"caption-attachment-664\" class=\"wp-caption-text\">Das Leben ist bunt, Elisabeth Berger<\/figcaption><\/figure>\n<p>F\u00fcr <a href=\"http:\/\/www.online-mit-tieren.com\" target=\"_blank\" rel=\"noopener\">Elisabeth Berger, Gr\u00fcnderin von Online mit Tieren<\/a>, sind das Erkl\u00e4rungsmodelle f\u00fcr l\u00e4ngst bekannte Ph\u00e4nomene. Telepathie und Fernwahrnehmung sind keine Erfindungen unserer Zeit. Wer dies seri\u00f6s im Rahmen einer Dienstleistung anbietet, braucht eine starke spirituelle Anbindung und muss hohen ethischen Anspr\u00fcchen gen\u00fcgen. Die Tierkommunikation ist ein wichtiger Bestandteil eines ganzheitlichen Leistungsspektrums, das Elisabeth Berger ihren KlientInnen angedeihen l\u00e4sst. Diese M\u00f6glichkeit \u00a0steht allen interessierten Menschen offen und die Fragen reichen dabei von der optimalen Farbe des Brustgeschirrs oder dem Lieblingsfutter bis zu hoch komplexen familiensystemischen Themen. Tiere und besonders die uns nahestehenden, mit in der Familie lebenden Hunde und Katzen, sind oft Platzhalter f\u00fcr \u00fcbergeordnete Themen.<\/p>\n<p>&nbsp;<\/p>\n<h4>Netzwerken zum Wohl des Hundes<\/h4>\n<p>Hilfreiche Netzwerke entstehen zu lassen bzw. anzusto\u00dfen, ist Elisabeth Berger ein echtes Anliegen. Denn die Tierkommunikation ist erg\u00e4nzend zu gutem Training ein wunderbares Werkzeug, wie sie uns anhand eines Fallbeispiels erz\u00e4hlt. Die Sicht des Tieres, durch die Tierkommunikatorin \u00fcbersetzt, ver\u00e4nderte die Trainingsgestaltung entscheidend. Auch wenn es um tier\u00e4rztliche Konsultationen geht, kann die Tierkommunikation wichtige Hinweise geben, wo gr\u00fcndliche \u00dcberpr\u00fcfung angeraten ist.<\/p>\n<p>&nbsp;<\/p>\n<h4>&#8222;Ich komme gerade von der Tierkommunikation&#8220;<\/h4>\n<p>Obwohl es inzwischen eine Reihe von Tier\u00e4rztInnen gibt, die der Tierkommunikation gegen\u00fcber aufgeschlossen sind oder sogar selbst bereits Ausbildungen absolviert haben, ist sie noch nicht selbstverst\u00e4ndlich. Auch TrainerInnen in der Hundeszene zeigen zunehmend Interesse an dieser Methode und sind bereit, wie im Fallbeispiel geschildert, mit der Tierkommunikatorin im Sinne von Mensch und Tier zusammenzuarbeiten oder gar selbst Ausbildungen zu absolvieren.<\/p>\n<figure id=\"attachment_665\" aria-describedby=\"caption-attachment-665\" style=\"width: 219px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Ulli-Karl-und-Hannah.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-665\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Ulli-Karl-und-Hannah-291x300.jpg\" alt=\"Ulrike Karl mit ihrer H\u00fcndin\" width=\"219\" height=\"226\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Ulli-Karl-und-Hannah-291x300.jpg 291w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Ulli-Karl-und-Hannah.jpg 616w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/a><figcaption id=\"caption-attachment-665\" class=\"wp-caption-text\">Ulrike Karl mit ihrer H\u00fcndin<\/figcaption><\/figure>\n<p>Das von Elisabeth Berger geschilderte Fallbeispiel wird auch noch aus einem anderen Blickwinkel beleuchtet: Die <a href=\"https:\/\/imleo.at\/\">Hundehalterin Ulrike Karl<\/a>, die mit Mann und Hund im Weinviertel zuhause ist, erz\u00e4hlt, wie sie die Synergie von Tierkommunikation und Training erlebt und empfunden hat.\u00a0 Auch \u00fcber ihre Zweifel spricht sie, z.B. \u00fcber die bange Frage \u201eLiebt mein Tier mich so, wie ich es liebe?\u201c\u00a0 An der Tierkommunikation selbst hatte sie keine Zweifel. Sp\u00e4testens als Elisabeth Berger w\u00e4hrend des Gespr\u00e4chs\u00a0 Details aus Leos Futtersch\u00fcssel ansprach, von denen sie nichts wissen konnte, war f\u00fcr die Hundehalterin klar, dass hier tats\u00e4chlich eine \u00dcbersetzung stattfand und die Information direkt von Leo, dem Hund, stammten.<\/p>\n<p><a href=\"https:\/\/imleo.at\/\" target=\"_blank\" rel=\"noopener\">Ulrike Karl <\/a>ermutigt Hundehalter, sich f\u00fcr die Tierkommunikation zu entscheiden.<\/p>\n<blockquote><p>\u201eIch freue mich f\u00fcr jeden, der sich entschliesst, sein Herz zu \u00f6ffnen und seinem Tier zuzuh\u00f6ren\u201c Ulrike Karl<\/p><\/blockquote>\n<figure id=\"attachment_670\" aria-describedby=\"caption-attachment-670\" style=\"width: 229px\" class=\"wp-caption alignright\"><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/UlliHanna.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-670\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/UlliHanna-300x265.jpg\" alt=\"Ulli und Hanna\" width=\"229\" height=\"202\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/UlliHanna-300x265.jpg 300w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/UlliHanna-768x678.jpg 768w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/UlliHanna-1024x903.jpg 1024w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/a><figcaption id=\"caption-attachment-670\" class=\"wp-caption-text\">Ulli und Hanna<\/figcaption><\/figure>\n<p>F\u00fcr sie selbst ist die Tierkommunikation prozessbegleitend seit vielen Jahren nicht mehr wegzudenken. Gerade Hunden, so meint sie, wird oft unterstellt, sie handelten aus B\u00f6swilligkeit und w\u00fcrden uns etwas \u201ezu Flei\u00df\u201c tun. Die Gespr\u00e4che mit den Tieren haben sie eines Besseren belehrt. Denn wenn es auch m\u00f6glich ist, dass Hunde mit Menschen \u201esprechen\u201c, denken sie dennoch weiterhin wie Hunde.<\/p>\n<blockquote><p>\u201eWir k\u00f6nnen viel von unseren Tieren lernen\u201c Ulrike Karl<\/p><\/blockquote>\n<h4><strong>Servicebox<\/strong><\/h4>\n<h5><strong>Zum Lesen:<\/strong><\/h5>\n<div>Kurt Kotrschal:<strong> Bindung zu Tieren, Einfach beste Freunde<\/strong>\u00a0 &#8211; Warum Menschen und andere Tiere einander verstehen<\/div>\n<div>Kurt Remele (Christliche Tierethik): <strong>Die W\u00fcrde des Tieres ist unantastbar<\/strong><\/div>\n<div>R\u00fcdiger Dahlke und Renato Pichler: <strong>Veganize your life<\/strong><\/div>\n<div>Lynne McTaggart: <strong>Das Nullpunktfeld<\/strong><\/div>\n<div><strong>Auf den Spuren der Intuition<\/strong>, Bayern Alpha, DVD \u2013 13 Folgen u.a. mit Hans Peter D\u00fcrr<\/div>\n<p>&nbsp;<\/p>\n<p><strong>Die Musik zur Sendung:<\/strong><\/p>\n<div>Al Jarreau \u2013 Mornin <a href=\"https:\/\/www.youtube.com\/watch?v=la0eUKD9kNw\">https:\/\/www.youtube.com\/watch?v=la0eUKD9kNw<\/a><\/div>\n<div>Miten &amp; Deva Premal &#8211; So Much Magnificence <a href=\"https:\/\/www.youtube.com\/watch?v=AG-YE8IiV5U\">https:\/\/www.youtube.com\/watch?v=AG-YE8IiV5U<\/a><\/div>\n<div><\/div>\n<p>Ein zus\u00e4tzlicher Tipp von Elisabeth Berger ist dieses wundersch\u00f6ne Video: Aman Ryusuke Seto \u00a0&#8211; Ho&#8217;oponopono <a href=\"http:\/\/www.youtube.com\/watch?v=ac5SGwRPv0o\">http:\/\/www.youtube.com\/watch?v=ac5SGwRPv0o<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Sendung anh\u00f6ren:<\/strong><\/p>\n<p><a href=\"https:\/\/cba.fro.at\/324062\" target=\"_blank\" rel=\"noopener\">Zur Aufzeichnung<\/a><\/p>\n<p>Live auf der Radiofabrik 107,5 oder per Livestream am 2. Mittwoch im Monat um 12.06 und am 2. Donnerstag im Monat um 19:06 Uhr. Nachh\u00f6ren ebenfalls \u00fcber die <a href=\"http:\/\/www.radiofabrik.at\">Radiofabrik <\/a>oder \u00fcber den <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/\">Hunderunde Blog<\/a>.<\/p>\n<p>Feedback und Kontakt: Karin Immler, <a href=\"http:\/\/www.knowwau.com\">www.knowwau.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Menschen, die mit Hunden sprechen Immer mehr Menschen w\u00fcnschen sich eine tiefe und innige Beziehung zu ihren Tieren. Das zeigt sich nicht nur im Trend zu gewaltfreien Trainingsmethoden sondern auch in der Bereitschaft, mehr und mehr eine ganzheitliche Sichtweise auf die Mensch-Tier-Beziehung einzunehmen. Die Wissenschaft besch\u00e4ftigt sich derzeit intensiv damit, wie Menschen und Hunde sich &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/\" class=\"more-link\"><span class=\"screen-reader-text\">Beziehungspflege &#8211; mit Hunden sprechen<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":682,"featured_media":668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[29815,40002,17698,21704,28619,18385,32095,40003,31102],"class_list":["post-661","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-elisabeth-berger","tag-ethik","tag-hund","tag-hunde","tag-hunde-erziehen","tag-hundeerziehung","tag-hundetraining","tag-telepathie","tag-tierkommunikation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Beziehungspflege - mit Hunden sprechen - Hunderunde<\/title>\n<meta name=\"description\" content=\"Tierkommunikation als Begleitung und Unterst\u00fctzung f\u00fcr den Alltag mit unseren Hunden, auch prozessbegleitend zu Training und Erziehung\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beziehungspflege - mit Hunden sprechen - Hunderunde\" \/>\n<meta property=\"og:description\" content=\"Tierkommunikation als Begleitung und Unterst\u00fctzung f\u00fcr den Alltag mit unseren Hunden, auch prozessbegleitend zu Training und Erziehung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/\" \/>\n<meta property=\"og:site_name\" content=\"Hunderunde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/karin.immler.7\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/knowwau\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-15T20:03:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-01T12:21:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Die-Hunde.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"907\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Karin Immler\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karin Immler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/\"},\"author\":{\"name\":\"Karin Immler\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"headline\":\"Beziehungspflege &#8211; mit Hunden sprechen\",\"datePublished\":\"2016-09-15T20:03:04+00:00\",\"dateModified\":\"2025-07-01T12:21:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/\"},\"wordCount\":788,\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2016\\\/09\\\/Die-Hunde.jpg\",\"keywords\":[\"Elisabeth Berger\",\"Ethik\",\"Hund\",\"Hunde\",\"Hunde erziehen\",\"Hundeerziehung\",\"Hundetraining\",\"Telepathie\",\"Tierkommunikation\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/\",\"name\":\"Beziehungspflege - mit Hunden sprechen - Hunderunde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2016\\\/09\\\/Die-Hunde.jpg\",\"datePublished\":\"2016-09-15T20:03:04+00:00\",\"dateModified\":\"2025-07-01T12:21:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"description\":\"Tierkommunikation als Begleitung und Unterst\u00fctzung f\u00fcr den Alltag mit unseren Hunden, auch prozessbegleitend zu Training und Erziehung\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2016\\\/09\\\/Die-Hunde.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2016\\\/09\\\/Die-Hunde.jpg\",\"width\":907,\"height\":666,\"caption\":\"Die Hunde, Elisabeth Berger\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2016\\\/09\\\/15\\\/beziehungspflege-mit-hunden-sprechen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Beziehungspflege &#8211; mit Hunden sprechen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\",\"name\":\"Hunderunde\",\"description\":\"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\",\"name\":\"Karin Immler\",\"sameAs\":[\"http:\\\/\\\/www.knowwau.com\",\"www.facebook.com\\\/knowwau\"],\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/author\\\/hunderunde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Beziehungspflege - mit Hunden sprechen - Hunderunde","description":"Tierkommunikation als Begleitung und Unterst\u00fctzung f\u00fcr den Alltag mit unseren Hunden, auch prozessbegleitend zu Training und Erziehung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/","og_locale":"de_DE","og_type":"article","og_title":"Beziehungspflege - mit Hunden sprechen - Hunderunde","og_description":"Tierkommunikation als Begleitung und Unterst\u00fctzung f\u00fcr den Alltag mit unseren Hunden, auch prozessbegleitend zu Training und Erziehung","og_url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/","og_site_name":"Hunderunde","article_publisher":"https:\/\/www.facebook.com\/karin.immler.7","article_author":"www.facebook.com\/knowwau","article_published_time":"2016-09-15T20:03:04+00:00","article_modified_time":"2025-07-01T12:21:46+00:00","og_image":[{"width":907,"height":666,"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Die-Hunde.jpg","type":"image\/jpeg"}],"author":"Karin Immler","twitter_misc":{"Verfasst von":"Karin Immler","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/#article","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/"},"author":{"name":"Karin Immler","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"headline":"Beziehungspflege &#8211; mit Hunden sprechen","datePublished":"2016-09-15T20:03:04+00:00","dateModified":"2025-07-01T12:21:46+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/"},"wordCount":788,"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Die-Hunde.jpg","keywords":["Elisabeth Berger","Ethik","Hund","Hunde","Hunde erziehen","Hundeerziehung","Hundetraining","Telepathie","Tierkommunikation"],"articleSection":["Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/","name":"Beziehungspflege - mit Hunden sprechen - Hunderunde","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/#primaryimage"},"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Die-Hunde.jpg","datePublished":"2016-09-15T20:03:04+00:00","dateModified":"2025-07-01T12:21:46+00:00","author":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"description":"Tierkommunikation als Begleitung und Unterst\u00fctzung f\u00fcr den Alltag mit unseren Hunden, auch prozessbegleitend zu Training und Erziehung","breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/#primaryimage","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Die-Hunde.jpg","contentUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2016\/09\/Die-Hunde.jpg","width":907,"height":666,"caption":"Die Hunde, Elisabeth Berger"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2016\/09\/15\/beziehungspflege-mit-hunden-sprechen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.radiofabrik.at\/hunderunde\/"},{"@type":"ListItem","position":2,"name":"Beziehungspflege &#8211; mit Hunden sprechen"}]},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/","name":"Hunderunde","description":"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.radiofabrik.at\/hunderunde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3","name":"Karin Immler","sameAs":["http:\/\/www.knowwau.com","www.facebook.com\/knowwau"],"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/author\/hunderunde\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/users\/682"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/comments?post=661"}],"version-history":[{"count":8,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/661\/revisions"}],"predecessor-version":[{"id":671,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/661\/revisions\/671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/media\/668"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/media?parent=661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/categories?post=661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/tags?post=661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}