{"id":897,"date":"2017-11-08T11:24:08","date_gmt":"2017-11-08T11:24:08","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/hunderunde\/?p=897"},"modified":"2020-04-20T17:34:43","modified_gmt":"2020-04-20T17:34:43","slug":"sicherheit-fuer-kind-und-hund","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/","title":{"rendered":"Sicherheit f\u00fcr Kind und Hund"},"content":{"rendered":"<h3>Sicherheit f\u00fcr Kind und Hund,<\/h3>\n<p>ein Thema, das immer wichtiger wird. Die Herangehensweise hat sich ja \u00fcber die Jahre ziemlich ver\u00e4ndert. Manchmal frage ich mich, wie das kommt. Ich kann mich nicht erinnern, dass man in meiner Kindheit gro\u00dfes Aufhebens darum gemacht hat. Jedenfalls nicht solange nichts ernsthaftes passiert ist.<\/p>\n<p>Polizeihauptkommissarin Claudia Dieth ist sozusagen Fachfrau auf diesem Gebiet. Sie ist verheiratet und hat einen Buben mit derzeit 6 Jahren. Und eine Malinoish\u00fcndin, die im Polizeidienst als Schutz &#8211; und Rauschgiftsp\u00fcrhund gef\u00fchrt wird &#8211; Aquilla. Frau Dieth engagiert sich dar\u00fcber hinaus als Vortragende f\u00fcr ein besseres Verst\u00e4ndnis zwischen Mensch und Hund. Ihre Polizeihundef\u00fchrerstaffel Schorndorf (Polizeipr\u00e4sidium Aalen) m\u00f6chte mit diesen\u00a0 Aufkl\u00e4rungskampangen zu bestimmten Hundethemen die Kompetenz bei den Hundebesitzern st\u00e4rken, um das Miteinander in unserer Gesellschaft zu verbessern. Dazu geh\u00f6rt vor allem der Respekt der HundehalterInnen gegen\u00fcber Mitmenschen mit und ohne Hund und ebenso dem eigenen Hund gegen\u00fcber, f\u00fcr den er die Verantwortung tr\u00e4gt.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>&#8222;Das oberste Ziel sollte sein: Respekt des Hundehalters gegen\u00fcber seinem eigenen Hund und Respekt auch gegen\u00fcber den Mitmenschen \u2013 mit und ohne Hund.&#8220; Claudia Dieth<\/p><\/blockquote>\n<p>Vorrangig geht es Frau Dieth um Kommunikation, darum dass HundehalterInnen verstehen wie es Ihrem Hund geht und was er Ihnen sagen m\u00f6chte. Auch eine tolle <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/Borsch\u00fcreMeinHundDRUCK.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Brosch\u00fcre &#8222;Mein Hund&#8220;<\/a> hat sie initiiert, die dar\u00fcber ber\u00e4t, worauf man VOR dem Hundekauf achten sollte.<\/p>\n<h3>&#8222;VersteHen, StaUnen, TraiNieren, EntDecken&#8220;<\/h3>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/cAurea-Verebes.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-903\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/cAurea-Verebes-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/cAurea-Verebes-300x300.png 300w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/cAurea-Verebes-150x150.png 150w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/cAurea-Verebes.png 727w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Area Verebes vom Verlag Canimos, ist Herausgeberin und Mit-Autorin eine Buchreihe f\u00fcr Kinder <a href=\"https:\/\/www.canimos.de\/shop\/\">&#8222;VersteHen, StaUnen, TraiNieren, EntDecken&#8220;<\/a>. Dar\u00fcber hinaus hat sie gemeinsam mit Andreas Baier ein Bisspr\u00e4ventionsprogramm entwickelt, das mithelfen soll, den Alltag mit Kind und Hund sicher zu gestalten. Sie ist verheiratet und hat drei S\u00f6hne und zwei Hunde und wei\u00df also ganz genau, wovon sie spricht.<\/p>\n<h3>And the winner is<\/h3>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/Buchreihe-Canimos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-907\" src=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/Buchreihe-Canimos-300x212.jpg\" alt=\"Buchreihe c) canimos.de\" width=\"300\" height=\"212\" srcset=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/Buchreihe-Canimos-300x212.jpg 300w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/Buchreihe-Canimos-768x543.jpg 768w, https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/Buchreihe-Canimos-1024x724.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Dieses Mal gibt es auch etwas zu gewinnen und zwar ein Buch aus der oben genannten Reihe. Um dieses Buch zu gewinnen, brauchen Sie lediglich unsere Gewinnfrage richtig zu beantworten. Also gut aufpassen, denn die Antwort auf die Frage, die h\u00f6ren Sie im Verlauf der Radiosendung. Wie lautet der Name des Projekts, das Aurea Verebes gemeinsam mit der Trainerin Nerina Aupperle ins Leben gerufen hat<\/p>\n<p style=\"padding-left: 60px\">a)\u00a0\u00a0\u00a0\u00a0\u00a0 Dogs and Kids<br \/>\nb)\u00a0\u00a0\u00a0\u00a0\u00a0 Kidogs<br \/>\nc)\u00a0\u00a0\u00a0\u00a0\u00a0 Kids and Dogs<\/p>\n<p>Senden Sie eine Email mit der richtigen Antwort an <a href=\"mailto:info@canimos.de\" target=\"_blank\" rel=\"noopener noreferrer\">info@canimos.de <\/a>und gewinnen Sie eines dieser tollen B\u00fccher.\u00a0 Einsendeschluss ist der 30. November 2017. Wir dr\u00fccken alle die Daumen \ud83d\ude42 .<\/p>\n<h3>Servicebox:<\/h3>\n<p>Aurea Verebes<br \/>\n<a href=\"http:\/\/www.canimos.de\">Canimos Verlag<\/a><br \/>\n<a href=\"http:\/\/www.canis-pacalis.de\">Canis Pacalis<\/a><br \/>\nFacebook: <a href=\"https:\/\/www.facebook.com\/sophia.verebes\" target=\"_blank\" rel=\"noopener noreferrer\">Aurea Verebes<\/a><\/p>\n<p><a href=\"https:\/\/ppaalen.polizei-bw.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Polizeihauptkommissarin Claudia Dieth<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/PolizeiAalen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook<\/a><br \/>\n<a href=\"https:\/\/www.facebook.com\/pg\/PolizeiAalen\/videos\/?ref=page_internal;http:\/\/medienportal-polizei.land-bw.de\/document\/Hund-im-Pkw\/59e79f2ec00ec06d053e148b0651c1a6\" target=\"_blank\" rel=\"noopener noreferrer\">Publikationen <\/a><\/p>\n<p><a href=\"http:\/\/www.online-hundeschule.net\/onlinekurse\/kind_und_hund_freunde\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kind und Hund &#8211; Freunde f\u00fcrs Leben<\/a><br \/>\nOnlinekurs \u00a0mit 19 Lektionen prall gef\u00fcllt mit Informationen und Tipps f\u00fcr einen harmonischen Familienalltag mit Kind(ern) und Hund(en).<\/p>\n<h3>Lesefutter:<\/h3>\n<p><strong>&#8222;VersteHen, StaUnen, TraiNieren, EntDecken&#8220;<\/strong> von Aurea Verebes, Maria Rehberger und Andreas Baier, Canimos Verlag<br \/>\n<strong>So klappts mit Kind und Hund<\/strong>, Dagmar Cutka, Cadmos Hundepraxis<br \/>\n<a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/Borsch\u00fcreMeinHundDRUCK.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Brosch\u00fcre \u201eMein Hund\u201c<\/a><br \/>\n<a href=\"https:\/\/www.knowwau.com\/kind-und-hund-idylle-oder-chaos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kind und Hund, Idylle oder Chaos, Karin Immler<\/a><br \/>\n<a href=\"http:\/\/www.knowwau.com\/kind-und-hund-sicherheit-geht-vor\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kind und Hund, Sicherheit geht vor, Karin Immler<\/a><\/p>\n<h3>Musik:<\/h3>\n<p>Ina M\u00fcller &#8211; H\u00e4tt\u2018 ich `nen Hund<br \/>\nJohn Shipe &#8211; Pit Bull Blues<br \/>\nWaylon Jennings &#8211; That dog won\u2019t hunt<\/p>\n<h3>Sendung anh\u00f6ren:<\/h3>\n<p>Live auf der <a href=\"http:\/\/www.radiofabrik.at\/home.html\">Radiofabrik<\/a> 107,5 oder per\u00a0<a class=\"broken_link\" href=\"http:\/\/www.radiofabrik.at\/programm0\/sendedaten.html#c5829\" target=\"_blank\" rel=\"noopener noreferrer\">APP<\/a> immer am 2. Mittwoch im Monat um 12:08 Uhr und am 2. Donnerstag im Monat um 19:08 Uhr. Nachh\u00f6ren ebenfalls \u00fcber die <a href=\"http:\/\/www.radiofabrik.at\/programm0\/sendungenvona-z\/hunderunde.html\">Radiofabrik,\u00a0<\/a>\u00fcber den <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hunderunde Blog\u00a0<\/a>oder direkt \u00fcber das <a href=\"https:\/\/cba.fro.at\/series\/hunderunde\">Archiv <\/a>.<\/p>\n<p>Feedback und Kontakt: Karin Immler,\u00a0 <a href=\"http:\/\/www.knowwau.com\">www.knowwau.com<\/a><\/p>\n<p>Hundewissen zum H\u00f6ren im <a href=\"https:\/\/anchor.fm\/knowwau\" target=\"_blank\" rel=\"noopener noreferrer\">Hundepodcast von know wau.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sicherheit f\u00fcr Kind und Hund, ein Thema, das immer wichtiger wird. Die Herangehensweise hat sich ja \u00fcber die Jahre ziemlich ver\u00e4ndert. Manchmal frage ich mich, wie das kommt. Ich kann mich nicht erinnern, dass man in meiner Kindheit gro\u00dfes Aufhebens darum gemacht hat. Jedenfalls nicht solange nichts ernsthaftes passiert ist. Polizeihauptkommissarin Claudia Dieth ist sozusagen &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/\" class=\"more-link\"><span class=\"screen-reader-text\">Sicherheit f\u00fcr Kind und Hund<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":682,"featured_media":902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[40061,28619,40059,17891,40057,40060,40058,29814],"class_list":["post-897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-aurea-verebes","tag-hunde-erziehen","tag-hundebisspraevention","tag-hundehaltung","tag-kind-und-hund","tag-polizeihunde","tag-sicherheit","tag-verantwortung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicherheit f\u00fcr Kind und Hund - Hunderunde<\/title>\n<meta name=\"description\" content=\"Sicherheit f\u00fcr Kind und Hund - ein wichtiges Thema. Was kann man als Eltern, Gro\u00dfeltern oder Tante mit Hund zu einem harmonischen Alltag beitragen?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicherheit f\u00fcr Kind und Hund - Hunderunde\" \/>\n<meta property=\"og:description\" content=\"Sicherheit f\u00fcr Kind und Hund - ein wichtiges Thema. Was kann man als Eltern, Gro\u00dfeltern oder Tante mit Hund zu einem harmonischen Alltag beitragen?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/\" \/>\n<meta property=\"og:site_name\" content=\"Hunderunde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/karin.immler.7\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/knowwau\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-08T11:24:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-20T17:34:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/c-Claudia-Dieth.png\" \/>\n\t<meta property=\"og:image:width\" content=\"795\" \/>\n\t<meta property=\"og:image:height\" content=\"656\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Karin Immler\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karin Immler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/\"},\"author\":{\"name\":\"Karin Immler\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"headline\":\"Sicherheit f\u00fcr Kind und Hund\",\"datePublished\":\"2017-11-08T11:24:08+00:00\",\"dateModified\":\"2020-04-20T17:34:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/\"},\"wordCount\":595,\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2017\\\/11\\\/c-Claudia-Dieth.png\",\"keywords\":[\"Aurea Verebes\",\"Hunde erziehen\",\"Hundebisspr\u00e4vention\",\"Hundehaltung\",\"Kind und Hund\",\"Polizeihunde\",\"Sicherheit\",\"Verantwortung\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/\",\"name\":\"Sicherheit f\u00fcr Kind und Hund - Hunderunde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2017\\\/11\\\/c-Claudia-Dieth.png\",\"datePublished\":\"2017-11-08T11:24:08+00:00\",\"dateModified\":\"2020-04-20T17:34:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\"},\"description\":\"Sicherheit f\u00fcr Kind und Hund - ein wichtiges Thema. Was kann man als Eltern, Gro\u00dfeltern oder Tante mit Hund zu einem harmonischen Alltag beitragen?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2017\\\/11\\\/c-Claudia-Dieth.png\",\"contentUrl\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/files\\\/2017\\\/11\\\/c-Claudia-Dieth.png\",\"width\":795,\"height\":656,\"caption\":\"Claudia Dieth\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/2017\\\/11\\\/08\\\/sicherheit-fuer-kind-und-hund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicherheit f\u00fcr Kind und Hund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/\",\"name\":\"Hunderunde\",\"description\":\"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/#\\\/schema\\\/person\\\/d68e6955fc348b87af98239a485f79f3\",\"name\":\"Karin Immler\",\"sameAs\":[\"http:\\\/\\\/www.knowwau.com\",\"www.facebook.com\\\/knowwau\"],\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/hunderunde\\\/author\\\/hunderunde\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicherheit f\u00fcr Kind und Hund - Hunderunde","description":"Sicherheit f\u00fcr Kind und Hund - ein wichtiges Thema. Was kann man als Eltern, Gro\u00dfeltern oder Tante mit Hund zu einem harmonischen Alltag beitragen?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/","og_locale":"de_DE","og_type":"article","og_title":"Sicherheit f\u00fcr Kind und Hund - Hunderunde","og_description":"Sicherheit f\u00fcr Kind und Hund - ein wichtiges Thema. Was kann man als Eltern, Gro\u00dfeltern oder Tante mit Hund zu einem harmonischen Alltag beitragen?","og_url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/","og_site_name":"Hunderunde","article_publisher":"https:\/\/www.facebook.com\/karin.immler.7","article_author":"www.facebook.com\/knowwau","article_published_time":"2017-11-08T11:24:08+00:00","article_modified_time":"2020-04-20T17:34:43+00:00","og_image":[{"width":795,"height":656,"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/c-Claudia-Dieth.png","type":"image\/png"}],"author":"Karin Immler","twitter_misc":{"Verfasst von":"Karin Immler","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/#article","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/"},"author":{"name":"Karin Immler","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"headline":"Sicherheit f\u00fcr Kind und Hund","datePublished":"2017-11-08T11:24:08+00:00","dateModified":"2020-04-20T17:34:43+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/"},"wordCount":595,"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/c-Claudia-Dieth.png","keywords":["Aurea Verebes","Hunde erziehen","Hundebisspr\u00e4vention","Hundehaltung","Kind und Hund","Polizeihunde","Sicherheit","Verantwortung"],"articleSection":["Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/","name":"Sicherheit f\u00fcr Kind und Hund - Hunderunde","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/#primaryimage"},"image":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/c-Claudia-Dieth.png","datePublished":"2017-11-08T11:24:08+00:00","dateModified":"2020-04-20T17:34:43+00:00","author":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3"},"description":"Sicherheit f\u00fcr Kind und Hund - ein wichtiges Thema. Was kann man als Eltern, Gro\u00dfeltern oder Tante mit Hund zu einem harmonischen Alltag beitragen?","breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/#primaryimage","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/c-Claudia-Dieth.png","contentUrl":"https:\/\/blog.radiofabrik.at\/hunderunde\/files\/2017\/11\/c-Claudia-Dieth.png","width":795,"height":656,"caption":"Claudia Dieth"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/2017\/11\/08\/sicherheit-fuer-kind-und-hund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/blog.radiofabrik.at\/hunderunde\/"},{"@type":"ListItem","position":2,"name":"Sicherheit f\u00fcr Kind und Hund"}]},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#website","url":"https:\/\/blog.radiofabrik.at\/hunderunde\/","name":"Hunderunde","description":"Gespr\u00e4che und Gedanken \u00fcber Hunde und Menschen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.radiofabrik.at\/hunderunde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/hunderunde\/#\/schema\/person\/d68e6955fc348b87af98239a485f79f3","name":"Karin Immler","sameAs":["http:\/\/www.knowwau.com","www.facebook.com\/knowwau"],"url":"https:\/\/blog.radiofabrik.at\/hunderunde\/author\/hunderunde\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/users\/682"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/comments?post=897"}],"version-history":[{"count":9,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/897\/revisions"}],"predecessor-version":[{"id":1357,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/posts\/897\/revisions\/1357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/media\/902"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/media?parent=897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/categories?post=897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/hunderunde\/wp-json\/wp\/v2\/tags?post=897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}