{"id":360,"date":"2011-11-07T13:37:22","date_gmt":"2011-11-07T13:37:22","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/?p=360"},"modified":"2011-11-12T14:17:39","modified_gmt":"2011-11-12T14:17:39","slug":"emotional-overdoze-chriss","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/","title":{"rendered":"Emotional Overdoze (chriss)"},"content":{"rendered":"<p><strong>Podcast\/Download: In der <a href=\"http:\/\/cba.fro.at\/51925\">Sendung vom Freitag, dem 11.11.2011<\/a> fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung&#8230; Also Dinge, die -wenn man sich ihnen ausliefert- einen st\u00e4rker machen und vorantreiben!\u00a0<\/strong><\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/CIMG7807.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-363 alignleft\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/CIMG7807-225x300.jpg\" alt=\"into the deep\" width=\"225\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/CIMG7807-225x300.jpg 225w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/CIMG7807-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><em>&#8222;Digging in the dirt. Stay with me, I need support. I&#8217;m digging in the dirt to find the paces I got hurt. Open up the places I got hurt&#8230;&#8220; &#8211; Peter Gabriel.<\/em> Man muss sich seinen <strong>Abgr\u00fcnden stellen<\/strong>, den Dingen, die einen verunsichern, einem Angst machen und die Luft nehmen. Man muss in die Dunkelheit gehen, hinab in den <strong>Orkus seiner Gef\u00fchle und dann ist man allein<\/strong>. <strong>Allein mit sich selbst<\/strong> und jenen Schatten, die man so gut versuchte zu verdr\u00e4ngen. Man muss ihnen ins Gesicht blicken um zu sehen, zu verstehen und weiter zu machen, <strong>St\u00e4rke und neue Kraft zu sch\u00f6pfen<\/strong>. Das schafft man allerdings nur, wenn man in den Spiegel der unverkl\u00e4rten Wahrheit blickt. Nur so und nicht anders. Und schon gar <strong>nicht durch irgendwelche Medikamente, &#8222;Seelenklempner&#8220; oder Beichtabnahmen!<\/strong><\/p>\n<p>Ja, wie ihr lesen k\u00f6nnt wird es (endlich) wieder <strong>tief, d\u00fcster und&#8230; authentisch!<\/strong> Denn nur in dem man <strong>alle, nicht nur die sch\u00f6nen, fr\u00f6hlichen und vergn\u00fcgten Seiten in und um sich annimmt, wird eine Aussage auch emotional verst\u00e4ndlich&#8230;<\/strong> Wir, als Gef\u00fchlsmenschen leiden irrsinnig unter jenen plastik\u00fcberzogenen und mit grinsender Fr\u00f6hlichkeit \u00fcbergossenen Emotionsvernichtern, die alles was wahr und individuell in ihnen ist, einfach abt\u00f6ten durch Markenvermarktungsaufbereitung und Gleichschrittmarsch. Wir wollen uns gegen diese <strong>allgemeine Verbl\u00f6dung des eigenen F\u00fchlens<\/strong> aussprechen und mal wieder so richtig im Dreck w\u00fchlen, so wie Peter Gabriel. Wieder einen <strong>Zwischenbericht unserer philosophischen Abenteuerreise durch eben jene Welt bringen, die bald einheitlich deppad sein wird <\/strong>und endlich wieder all unseren Frust, Grant, unsere Abneigung und unsere dunklen Gedanken mit euch teilen&#8230;<\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/DSCN0192.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-372 alignleft\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/DSCN0192-225x300.jpg\" alt=\"in the shadow\" width=\"225\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/DSCN0192-225x300.jpg 225w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/DSCN0192-768x1024.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/DSCN0192.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>Nat\u00fcrlich sollen <strong>all unsere Tiefen nicht ganz ohne Lichtblicke bleiben&#8230;<\/strong>\u00a0Wir werden sehen, wohin uns unsere Playlist f\u00fchlt, aber so viel sei jetzt schon verraten: <strong>Von aush\u00e4ngiger Schei\u00dfe \u00fcber verinnerlichten Schmerz bis zum powervollen Schlu\u00dfakkord<\/strong> der in einem seelischen Zerst\u00fcckelungsprozess endet, haben wir eine wunderbare Auswahl an depremierten, verblutenden, schreienden und davonlaufenwollenden Musiken von <a href=\"http:\/\/www.youtube.com\/watch?v=EpKZ2H7CC3s\">Patti Smith<\/a>, <a href=\"http:\/\/blog.radiofabrik.at\/artarium\/2011\/06\/25\/peter-gabriel-art-of-inspiration\/\">Peter Gabriel<\/a>, <a href=\"http:\/\/www.kttunstall.com\/\">KT Tunstall<\/a>, <a href=\"http:\/\/de.wikipedia.org\/wiki\/Leslie_Feist\">Feist<\/a> etc. f\u00fcr euch&#8230;<\/p>\n<p>Also, wer sich traut oder gerade nichts zu tun hat, unterwegs nach irgendwo ist, sich gerade beim orgeln langweilt oder uns beide und <strong>unsere Sendung<\/strong> einfach mag und sch\u00e4tzt, der oder die soll doch einschalten! Wir haften allerdings nicht f\u00fcr irgendwelche Entdummungen und unvorhergesehene Gef\u00fchlswahrnehmungen die zu einen <strong>Rausch der Erkenntnis<\/strong> f\u00fchren!<\/p>\n<p>Danke und Baba&#8230; Hear you \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":220,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4015,1,71],"tags":[4021,4019,4023,4022],"class_list":["post-360","post","type-post","status-publish","format-standard","hentry","category-in-produktion","category-uncategorized","category-sendung","tag-depression","tag-inclusion","tag-rage","tag-revolution"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung... Also Dinge, die\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"chriss\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta property=\"og:description\" content=\"Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung... Also Dinge, die\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-11-07T13:37:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-11-12T14:17:39+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung... Also Dinge, die\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#blogposting\",\"name\":\"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher\",\"headline\":\"Emotional Overdoze (chriss)\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/files\\\/2011\\\/11\\\/CIMG7807-225x300.jpg\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#articleImage\"},\"datePublished\":\"2011-11-07T13:37:22+00:00\",\"dateModified\":\"2011-11-12T14:17:39+00:00\",\"inLanguage\":\"de-DE\",\"commentCount\":5,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#webpage\"},\"articleSection\":\"In Produktion, Passt in keine Schachtel, Sendung, depression, inclusion, rage, revolution\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Passt in keine Schachtel\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#listItem\",\"name\":\"Emotional Overdoze (chriss)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#listItem\",\"position\":3,\"name\":\"Emotional Overdoze (chriss)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/\",\"name\":\"chriss\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a706dcfa40bd8235e6765236f16763d67ab490ceea2ae4bda9704351f5e4f32?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"chriss\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/\",\"name\":\"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher\",\"description\":\"Podcast\\\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\\u00f6dliche Abweisung... Also Dinge, die\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/emotional-overdoze-chriss\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\"},\"datePublished\":\"2011-11-07T13:37:22+00:00\",\"dateModified\":\"2011-11-12T14:17:39+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher","description":"Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung... Also Dinge, die","canonical_url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#blogposting","name":"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher","headline":"Emotional Overdoze (chriss)","author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author"},"publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2011\/11\/CIMG7807-225x300.jpg","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#articleImage"},"datePublished":"2011-11-07T13:37:22+00:00","dateModified":"2011-11-12T14:17:39+00:00","inLanguage":"de-DE","commentCount":5,"mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#webpage"},"articleSection":"In Produktion, Passt in keine Schachtel, Sendung, depression, inclusion, rage, revolution"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","position":1,"name":"Home","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","position":2,"name":"Passt in keine Schachtel","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#listItem","name":"Emotional Overdoze (chriss)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#listItem","position":3,"name":"Emotional Overdoze (chriss)","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}}]},{"@type":"Organization","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/","name":"chriss","image":{"@type":"ImageObject","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3a706dcfa40bd8235e6765236f16763d67ab490ceea2ae4bda9704351f5e4f32?s=96&d=mm&r=pg","width":96,"height":96,"caption":"chriss"}},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#webpage","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/","name":"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher","description":"Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung... Also Dinge, die","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author"},"creator":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author"},"datePublished":"2011-11-07T13:37:22+00:00","dateModified":"2011-11-12T14:17:39+00:00"},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","og:type":"article","og:title":"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher","og:description":"Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung... Also Dinge, die","og:url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/","article:published_time":"2011-11-07T13:37:22+00:00","article:modified_time":"2011-11-12T14:17:39+00:00","twitter:card":"summary","twitter:title":"Emotional Overdoze (chriss) - Nachtfahrt Perlentaucher","twitter:description":"Podcast\/Download: In der Sendung vom Freitag, dem 11.11.2011 fahren Norbert K Hund und Christopher Schmall hinab in die tiefen Abgr\u00fcnde und Abscheulichkeiten der menschlichen Seele. Eine nachtdunkle Begreifung des Seins und eine Bejahung aller Gef\u00fchle die allzu gerne unter den Teppich gekehrt werden: Weltschmerz, Verzweiflung, Ausweglosigkeit, tiefe Trauer, versteinernde Angst, t\u00f6dliche Abweisung... Also Dinge, die"},"aioseo_meta_data":{"post_id":"360","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-09 20:34:32","updated":"2025-06-04 02:34:56","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/\" title=\"Passt in keine Schachtel\">Passt in keine Schachtel<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEmotional Overdoze (chriss)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt"},{"label":"Passt in keine Schachtel","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/"},{"label":"Emotional Overdoze (chriss)","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/emotional-overdoze-chriss\/"}],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/users\/220"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/comments?post=360"}],"version-history":[{"count":24,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/360\/revisions"}],"predecessor-version":[{"id":389,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/360\/revisions\/389"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/categories?post=360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/tags?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}