{"id":5941,"date":"2016-06-14T19:16:38","date_gmt":"2016-06-14T19:16:38","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/?p=5941"},"modified":"2016-06-14T23:58:32","modified_gmt":"2016-06-14T23:58:32","slug":"mondfallsuechtig-chriss","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/","title":{"rendered":"Mondfalls\u00fcchtig &#8211; Nachwort"},"content":{"rendered":"<p><strong>Ein Nachwort zur <a href=\"https:\/\/cba.fro.at\/317922\">Nachtfahrt vom Freitag, 10. Juni<\/a><\/strong><\/p>\n<p>Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen aufgef\u00e4delt, Korallenkette viel feiner als gedacht, ein Hauch nur \/ Wimpernt\u00e4uschung, du schreitest Samt<\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9459.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5942\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9459-225x300.jpg\" alt=\"moonchild\" width=\"225\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9459-225x300.jpg 225w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9459-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a>karamellisiertes Schweigen. <em>Vanaprastham.<\/em> Trommelnde Morgensucht w\u00e4hrend Radierungen, hier zeigt sich auch wieder meine Liebe : nocturnales Verhalten, vielleicht mehr als Lebensgewohnheit, vielleicht ja Instinkte der Nacht, die sich ergie\u00dfen, \u00fcber mich str\u00f6men, so gl\u00e4nzend Rabenfedern in erfundenen Gassen. Nicht nur Realit\u00e4t l\u00e4sst sich biegen, keucht die alternde Entendame, der Kronkorken nickt, als ich mich n\u00e4hernd : nahtloser Bruch, dass B\u00e4ume schweben, Mondhase oh wach \u00fcber uns! Mein Herz dargeboten auf dem Altar der Sprache, noch schl\u00e4gt es, vernarbt, zart, wer wiegt mir das Wohl, die Freude, wer die Last, das Fallen? M\u00f6glich, dass Schatten hinter mir grinsen, mit wilden Augen; Kopf gehoben und zur\u00fcck in ein anderes Ich oder wie viele Leben kann ein Mensch f\u00fcllen? <em>Aufgeh\u00f6rt mit dem Denken w\u00e4hrend des Denkens<\/em>, so stiehlt sich Zeit, so durch die Finger, bald l\u00e4uten die Gl\u00f6ckner; angeregt, beschleunigt durch leuchtende Stunden, welch Sturz in den Himmel! Diese stille Sucht, gar mondfalls\u00fcchtig, erinnernd an Haikus durch winterliche Flusslande<\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9420.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5944\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9420-300x225.jpg\" alt=\"birth\" width=\"300\" height=\"225\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9420-300x225.jpg 300w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9420-768x576.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9420-1024x768.jpg 1024w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9420-400x300.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>und all das Vergessen, all den Vergessenen, den Verstummten, den Ge\u00e4chteten : was da wuchert in meinem Kopf, neben Lichtmandalas gestreifte Farbandeutung ros\u00e9 reifblau, das Knistern der Stille vor dem Schlaf, in der Fr\u00fch vor dem Schlaf, sieben \/ siegen \u00fcber <em>Schlafkunst<\/em>, Versuch einer Feststellung, zu Asche, zu Wasser, kaum saugt man die Gr\u00e4ser, die gl\u00e4sernen Strahlen, die Schalen in Spiegelung, wohl metallische Kl\u00e4nge sinken ins Ohr \u2026 ihre Worte ber\u00fchren etwas ganz tief in mir, wie Dunkel, das schon wieder strahlend \u2026 ich werde bald ruhen, es wandelt sich viel, halbfeuchter Asphalt unter den Kronen der Stadt, der kn\u00f6cherne Traumf\u00e4nger in perpetuierendem Kreisen, von Geisterhauch; so manches in regen Zust\u00e4nden, ein Umwenden und -w\u00e4lzen bis sich die Wellen dann gl\u00e4tten unter gebl\u00fcmten Himmeln, in Poesie verbunden<\/p>\n<p>&#8211; Christopher Schmall<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":220,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4015,1,71],"tags":[4026,7594,4045,4046,4035,4028,4016,83,4020,4044,22508,4040,22475,4014,4039],"class_list":["post-5941","post","type-post","status-publish","format-standard","hentry","category-in-produktion","category-uncategorized","category-sendung","tag-ambivalent","tag-auf-der-suche","tag-be-greifen","tag-das-kreative-vakuum","tag-das-leben-lebt","tag-ernst-jandl","tag-inbetween","tag-inteam","tag-live-im-studio","tag-magische-phantasie","tag-nachtaktiv","tag-selbsterkenntnis","tag-traumweltreisen","tag-unterwegs","tag-zusammen"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"chriss\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mondfalls\u00fcchtig \u2013 Nachwort - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta property=\"og:description\" content=\"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-06-14T19:16:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-06-14T23:58:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mondfalls\u00fcchtig \u2013 Nachwort - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#blogposting\",\"name\":\"Mondfalls\\u00fcchtig \\u2013 Nachwort - Nachtfahrt Perlentaucher\",\"headline\":\"Mondfalls\\u00fcchtig &#8211; Nachwort\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/files\\\/2016\\\/06\\\/CIMG9459-225x300.jpg\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#articleImage\"},\"datePublished\":\"2016-06-14T19:16:38+00:00\",\"dateModified\":\"2016-06-14T23:58:32+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#webpage\"},\"articleSection\":\"In Produktion, Passt in keine Schachtel, Sendung, ambivalent, auf der suche, be-greifen, das kreative vakuum, das leben lebt, ernst jandl, inbetween, inteam, live im studio, magische phantasie, nachtaktiv, selbsterkenntnis, traumweltreisen, unterwegs, zusammen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Passt in keine Schachtel\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#listItem\",\"name\":\"Mondfalls\\u00fcchtig &#8211; Nachwort\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#listItem\",\"position\":3,\"name\":\"Mondfalls\\u00fcchtig &#8211; Nachwort\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/\",\"name\":\"chriss\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a706dcfa40bd8235e6765236f16763d67ab490ceea2ae4bda9704351f5e4f32?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"chriss\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/\",\"name\":\"Mondfalls\\u00fcchtig \\u2013 Nachwort - Nachtfahrt Perlentaucher\",\"description\":\"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\\u00dfe l\\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\\u00f6rt man das Singen des Schreibens und Pausen wie Perlen\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/mondfallsuechtig-chriss\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/chriss\\\/#author\"},\"datePublished\":\"2016-06-14T19:16:38+00:00\",\"dateModified\":\"2016-06-14T23:58:32+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mondfalls\u00fcchtig \u2013 Nachwort - Nachtfahrt Perlentaucher","description":"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen","canonical_url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#blogposting","name":"Mondfalls\u00fcchtig \u2013 Nachwort - Nachtfahrt Perlentaucher","headline":"Mondfalls\u00fcchtig &#8211; Nachwort","author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author"},"publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/06\/CIMG9459-225x300.jpg","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#articleImage"},"datePublished":"2016-06-14T19:16:38+00:00","dateModified":"2016-06-14T23:58:32+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#webpage"},"articleSection":"In Produktion, Passt in keine Schachtel, Sendung, ambivalent, auf der suche, be-greifen, das kreative vakuum, das leben lebt, ernst jandl, inbetween, inteam, live im studio, magische phantasie, nachtaktiv, selbsterkenntnis, traumweltreisen, unterwegs, zusammen"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","position":1,"name":"Home","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","position":2,"name":"Passt in keine Schachtel","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#listItem","name":"Mondfalls\u00fcchtig &#8211; Nachwort"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#listItem","position":3,"name":"Mondfalls\u00fcchtig &#8211; Nachwort","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}}]},{"@type":"Organization","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/","name":"chriss","image":{"@type":"ImageObject","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3a706dcfa40bd8235e6765236f16763d67ab490ceea2ae4bda9704351f5e4f32?s=96&d=mm&r=pg","width":96,"height":96,"caption":"chriss"}},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#webpage","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/","name":"Mondfalls\u00fcchtig \u2013 Nachwort - Nachtfahrt Perlentaucher","description":"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author"},"creator":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/chriss\/#author"},"datePublished":"2016-06-14T19:16:38+00:00","dateModified":"2016-06-14T23:58:32+00:00"},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","og:type":"article","og:title":"Mondfalls\u00fcchtig \u2013 Nachwort - Nachtfahrt Perlentaucher","og:description":"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen","og:url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/","article:published_time":"2016-06-14T19:16:38+00:00","article:modified_time":"2016-06-14T23:58:32+00:00","twitter:card":"summary","twitter:title":"Mondfalls\u00fcchtig \u2013 Nachwort - Nachtfahrt Perlentaucher","twitter:description":"Ein Nachwort zur Nachtfahrt vom Freitag, 10. Juni Angst vor dem Tod hatte ich eigentlich nie. Angst vor dem Sterben, meine ich, die Stra\u00dfe l\u00f6st sich, auf unbestimmte Zeit verborgt euer Sch\u00f6pfen, von Wasser oder betrittst fremde Welt, zum ersten Mal, unbekannt noch, unbefleckt; da h\u00f6rt man das Singen des Schreibens und Pausen wie Perlen"},"aioseo_meta_data":{"post_id":"5941","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-09 20:41:13","updated":"2025-06-04 02:43:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/\" title=\"Passt in keine Schachtel\">Passt in keine Schachtel<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMondfalls\u00fcchtig \u2013 Nachwort\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt"},{"label":"Passt in keine Schachtel","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/"},{"label":"Mondfalls\u00fcchtig &#8211; Nachwort","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/mondfallsuechtig-chriss\/"}],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/5941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/users\/220"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/comments?post=5941"}],"version-history":[{"count":7,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/5941\/revisions"}],"predecessor-version":[{"id":5951,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/5941\/revisions\/5951"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/media?parent=5941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/categories?post=5941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/tags?post=5941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}