{"id":6138,"date":"2016-10-11T11:46:55","date_gmt":"2016-10-11T11:46:55","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/?p=6138"},"modified":"2016-10-15T10:12:16","modified_gmt":"2016-10-15T10:12:16","slug":"spaetlese","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/","title":{"rendered":"Sp\u00e4tlese"},"content":{"rendered":"<p><strong>&gt; Sendung: <a href=\"https:\/\/cba.fro.at\/326034\" target=\"_blank\">Perlentaucher Nachtfahrt vom Freitag, 14. Oktober<\/a><\/strong> &#8211; <strong>Sp\u00e4tlese mit Winzer<\/strong> hei\u00dft ein Gedicht von <strong>Anna Breitenbach<\/strong>, welches speziell f\u00fcr die <strong>heurigen<\/strong> (sic) <a href=\"http:\/\/www.swr.de\/kunscht\/literaturtage-weinstadt-dichter-im-weinberg\/-\/id=12539036\/did=17941306\/nid=12539036\/v0d2a9\/index.html\" target=\"_blank\"><strong>Literaturtage in Weinstadt<\/strong><\/a> (sicsic) entstanden ist. In der <a href=\"http:\/\/blog.radiofabrik.at\/artarium\/2010\/04\/29\/kunnst\/\" target=\"_blank\"><strong>unseren Untertiteln<\/strong><\/a> ziemlich artverwandten<strong> TV-Sendung <a href=\"http:\/\/www.swr.de\/kunscht\/-\/id=13831134\/9dhwn6\/index.html\" target=\"_blank\">\u201cKunscht\u201d<\/a><\/strong> berichtete seine unstillbare Umtriebigkeit <strong>Denis Scheck<\/strong> \u00fcber <strong>diverse Dichterlesungen<\/strong>, f\u00fcr welche zuvor <strong>die Autor_innen beim Lesen und Keltern des Weins<\/strong> mitgewirkt und so ihre Eindr\u00fccke <strong>in wohlvergorenes Wortwerk<\/strong> <strong>verwandelt<\/strong> haben. Auf diesem poetischen Terroir kommt es zu allerlei Assoziationen mit Fachbegriffen wie etwa <strong>Trockenstress<\/strong>, <strong>S\u00fc\u00dff\u00e4ule<\/strong> oder <strong>Geschein<\/strong>. Und ich dachte, dass es bei <strong>Wein<\/strong>, <strong>Wort und Gesang<\/strong> um <a href=\"https:\/\/cba.fro.at\/series\/stoned-poets\" target=\"_blank\"><strong>Stoned Poets (Dichte Dichter)<\/strong><\/a> geht im Sinne des <strong>trunkenen H. C. Artmann<\/strong>, dem man <strong>nach seinem Vortrag<\/strong> vom Podium helfen musste.<\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6144\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen-300x300.jpg\" alt=\"herbsthasen\" width=\"300\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen-300x300.jpg 300w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen-150x150.jpg 150w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen-768x768.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen-1024x1024.jpg 1024w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Was also k\u00f6nnen <strong>wir Herbsthasen<\/strong> als <strong>Sp\u00e4tlese<\/strong> aufbereiten? Vor allem, ohne allzu wortw\u00f6rtlich ins Weinfass zu fallen. Es ist <strong>sp\u00e4t<\/strong> und wir <strong>lesen? <\/strong>Vielleicht <strong>Handverlesenes<\/strong> aus dem <strong>Fetzenspiel mit dem Mozartstaat? <\/strong>Die <strong>Essenz des Rosinenweins<\/strong> aus <strong>Georg Trakls Drogentopf?<\/strong> Eigenes oder Fremdes, <strong>Angeeignetes<\/strong> oder <strong>Befremdliches<\/strong>, <strong>\u00dcbersetztes<\/strong> oder <strong>Vorletztes<\/strong> oder l\u00e4ngst <strong>Zerfetztes?<\/strong> <strong>\u00dcber Oderhaupt<\/strong> ins <strong>Restdeutsch<\/strong> <strong>des Ostens<\/strong> dichteren <strong>Grobschnitt?<\/strong><\/p>\n<p><strong>Ein H\u00e4schen<\/strong> von alledem, damits <strong>ausgewogen und n\u00e4hrwert<\/strong> bleibt. Und zudem noch, was uns <strong>ein-<\/strong>, <strong>ab- und zuf\u00e4llt<\/strong>, damits nicht fad wird, so ganz <strong>ohne Weltrum und Kugel<\/strong>. Es ist ja immer ein <strong>Zwischenraum jenseits der Definitionen<\/strong>, den es genau deshalb <strong>zu bewohnen gilt<\/strong>. N\u00fcchtern betrachtet <strong>kann auch der Rausch verhandelt werden<\/strong>, ohne ihn zu verteufeln &#8211; oder ihm zu verfallen. &#8211; <strong>Im Hinblick darauf Georg Trakls Briefzitat<\/strong>:<\/p>\n<p><em> \u201cDass es Winter und kalt wird, sp\u00fcre ich an der abendlichen Weinheizung. Vorgestern habe ich 10 (sage! Zehn) Viertel Roten getrunken. Um vier Uhr morgens habe ich auf meinem Balkon ein Mond und Frostbad genommen und am Morgen endlich ein herrliches Gedicht geschrieben, das vor K\u00e4lte schebbert.\u201d<\/em><\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Mozart-Sp\u00e4tlese.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-6153\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Mozart-Sp\u00e4tlese-225x300.jpg\" alt=\"mozart-spaetlese\" width=\"225\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Mozart-Sp\u00e4tlese-225x300.jpg 225w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Mozart-Sp\u00e4tlese-768x1024.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Mozart-Sp\u00e4tlese.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><strong>Sp\u00e4tlese<\/strong> kann in unserem Fall aber auch <strong>Nachlese<\/strong>, <strong>Protestsongperlen<\/strong>&#8211; oder gar <strong>Torkelb\u00e4renauslese<\/strong> bedeuten. Der uns nicht ganz ungel\u00e4ufige <strong>Herr Blumenau<\/strong> ergeht sich n\u00e4mlich <strong>im Nachfeld der diesj\u00e4hrigen K\u00fcr<\/strong> von <a href=\"https:\/\/www.youtube.com\/watch?v=pBLJNe8hsKE\" target=\"_blank\"><strong>Sarah Leschs \u201cTestament\u201d<\/strong><\/a> in <strong>eigenwilligen Argumenten<\/strong>, warum er diesem Lied <strong>genau null Punkte<\/strong> zugestand und warum es ihn auch nicht wundert, dass es inzwischen von <strong>rechtsrechten Gruppen<\/strong> f\u00fcr deren Weltsicht <strong>vereinnahmt<\/strong> wird. Das l\u00e4ge, so <a href=\"http:\/\/fm4.orf.at\/stories\/1773433\/\" target=\"_blank\"><strong>der t\u00e4gliche Blumenau in seinem Artikel<\/strong><\/a>, von vornherein an Text und <strong>Haltung<\/strong> des Songs. Darob mag man <strong>sich ein Bild machen<\/strong>.<\/p>\n<p>W\u00e4hrend wir uns wiederum <strong>einen ureigenen<\/strong> (und etwas anderen) <strong>Contest<\/strong> schneidern, in dem es <strong>um genau nichts<\/strong> geht, au\u00dfer um unsere <strong>gemeinsame Lust an der Freud<\/strong>. <strong>K\u00fcren wir halt das aush\u00e4ngigste <a href=\"http:\/\/www.taz.de\/!158362\/\" target=\"_blank\">K\u00fcrzesth\u00f6rspiel<\/a> des heurigen<\/strong> (hic) <strong>Weinherbsts!<\/strong> <strong>Mit einem vollen Radio ist laut stinken.<\/strong> &#8211; <strong>Dazu Georg Trakls<\/strong> <strong>Wienverkostung:<\/strong><\/p>\n<p><em>\u201cIn Wien aber \u201cstrahlt\u201d die Sonne am \u201cheiteren\u201d Himmel und die \u201cweiche Melancholie\u201d des Wienerwaldes ist auch nicht \u201cohne\u201d. Beim Heurigen freut sich das \u201cgoldene\u201d Herz und wenn dort die \u201cschmachtenden Weisen\u201d erklingen, so denke o Mensch daran, dass es bei den \u201cwackeren \u00c4lplern\u201d schneit und grimmig kalt ist. O! wie weh ist die Welt, wie wahnig das Weh, wie weltlich der Wahn.\u201d<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober &#8211; Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4015,1,77,71],"tags":[4026,4046,4052,22512,4041,4030],"class_list":["post-6138","post","type-post","status-publish","format-standard","hentry","category-in-produktion","category-uncategorized","category-projekt","category-sendung","tag-ambivalent","tag-das-kreative-vakuum","tag-empowerment","tag-kuerzesthoerspiel","tag-scheinwelt-entzaubern","tag-wagnis"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \u00fcber diverse Dichterlesungen, f\u00fcr welche zuvor die Autor_innen beim Lesen und\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"artarium\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sp\u00e4tlese - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta property=\"og:description\" content=\"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \u00fcber diverse Dichterlesungen, f\u00fcr welche zuvor die Autor_innen beim Lesen und\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-10-11T11:46:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-10-15T10:12:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sp\u00e4tlese - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \u00fcber diverse Dichterlesungen, f\u00fcr welche zuvor die Autor_innen beim Lesen und\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#blogposting\",\"name\":\"Sp\\u00e4tlese - Nachtfahrt Perlentaucher\",\"headline\":\"Sp\\u00e4tlese\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/files\\\/2016\\\/10\\\/Herbsthasen-300x300.jpg\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#articleImage\"},\"datePublished\":\"2016-10-11T11:46:55+00:00\",\"dateModified\":\"2016-10-15T10:12:16+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#webpage\"},\"articleSection\":\"In Produktion, Passt in keine Schachtel, Projekt, Sendung, ambivalent, das kreative vakuum, empowerment, k\\u00fcrzesth\\u00f6rspiel, scheinwelt entzaubern, wagnis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Passt in keine Schachtel\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#listItem\",\"name\":\"Sp\\u00e4tlese\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#listItem\",\"position\":3,\"name\":\"Sp\\u00e4tlese\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/\",\"name\":\"artarium\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"artarium\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/\",\"name\":\"Sp\\u00e4tlese - Nachtfahrt Perlentaucher\",\"description\":\"> Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\\u00e4tlese mit Winzer hei\\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \\u201cKunscht\\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \\u00fcber diverse Dichterlesungen, f\\u00fcr welche zuvor die Autor_innen beim Lesen und\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/spaetlese\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"datePublished\":\"2016-10-11T11:46:55+00:00\",\"dateModified\":\"2016-10-15T10:12:16+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sp\u00e4tlese - Nachtfahrt Perlentaucher","description":"> Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \u00fcber diverse Dichterlesungen, f\u00fcr welche zuvor die Autor_innen beim Lesen und","canonical_url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#blogposting","name":"Sp\u00e4tlese - Nachtfahrt Perlentaucher","headline":"Sp\u00e4tlese","author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2016\/10\/Herbsthasen-300x300.jpg","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#articleImage"},"datePublished":"2016-10-11T11:46:55+00:00","dateModified":"2016-10-15T10:12:16+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#webpage"},"articleSection":"In Produktion, Passt in keine Schachtel, Projekt, Sendung, ambivalent, das kreative vakuum, empowerment, k\u00fcrzesth\u00f6rspiel, scheinwelt entzaubern, wagnis"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","position":1,"name":"Home","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","position":2,"name":"Passt in keine Schachtel","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#listItem","name":"Sp\u00e4tlese"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#listItem","position":3,"name":"Sp\u00e4tlese","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}}]},{"@type":"Organization","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/","name":"artarium","image":{"@type":"ImageObject","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=mm&r=pg","width":96,"height":96,"caption":"artarium"}},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#webpage","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/","name":"Sp\u00e4tlese - Nachtfahrt Perlentaucher","description":"> Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \u00fcber diverse Dichterlesungen, f\u00fcr welche zuvor die Autor_innen beim Lesen und","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"creator":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"datePublished":"2016-10-11T11:46:55+00:00","dateModified":"2016-10-15T10:12:16+00:00"},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","og:type":"article","og:title":"Sp\u00e4tlese - Nachtfahrt Perlentaucher","og:description":"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \u00fcber diverse Dichterlesungen, f\u00fcr welche zuvor die Autor_innen beim Lesen und","og:url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/","article:published_time":"2016-10-11T11:46:55+00:00","article:modified_time":"2016-10-15T10:12:16+00:00","twitter:card":"summary","twitter:title":"Sp\u00e4tlese - Nachtfahrt Perlentaucher","twitter:description":"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. Oktober - Sp\u00e4tlese mit Winzer hei\u00dft ein Gedicht von Anna Breitenbach, welches speziell f\u00fcr die heurigen (sic) Literaturtage in Weinstadt (sicsic) entstanden ist. In der unseren Untertiteln ziemlich artverwandten TV-Sendung \u201cKunscht\u201d berichtete seine unstillbare Umtriebigkeit Denis Scheck \u00fcber diverse Dichterlesungen, f\u00fcr welche zuvor die Autor_innen beim Lesen und"},"aioseo_meta_data":{"post_id":"6138","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-09 20:41:14","updated":"2025-06-04 02:43:06","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/\" title=\"Passt in keine Schachtel\">Passt in keine Schachtel<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSp\u00e4tlese\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt"},{"label":"Passt in keine Schachtel","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/"},{"label":"Sp\u00e4tlese","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/spaetlese\/"}],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/6138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/comments?post=6138"}],"version-history":[{"count":40,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/6138\/revisions"}],"predecessor-version":[{"id":6180,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/6138\/revisions\/6180"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/media?parent=6138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/categories?post=6138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/tags?post=6138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}