{"id":6562,"date":"2017-06-05T20:44:28","date_gmt":"2017-06-05T20:44:28","guid":{"rendered":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/?p=6562"},"modified":"2018-04-09T13:35:30","modified_gmt":"2018-04-09T13:35:30","slug":"velvet-goldmine","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/","title":{"rendered":"Velvet Goldmine"},"content":{"rendered":"<p><strong>&gt; Sendung: <a href=\"https:\/\/cba.fro.at\/342731\" target=\"_blank\" rel=\"noopener\">Perlentaucher Nachtfahrt vom Freitag, 9. Juni<\/a><\/strong> &#8211; Auf den Spuren des <strong>Kultfilms <a href=\"https:\/\/www.youtube.com\/watch?v=8VyIW5_sIvo\" target=\"_blank\" rel=\"noopener noreferrer\">Velvet Goldmine<\/a><\/strong> <strong>w\u00fcrdigen<\/strong> wir die <strong>sexuelle Ambivalenz<\/strong> in der Popkultur &#8211; und <strong>w\u00fcrgen<\/strong> am <strong>heteronormativen Durchschnitt<\/strong> einer <strong>bumsdummen Gesellschaft<\/strong> aus <strong>Massenbl\u00f6dien<\/strong>, <strong>Quassel\u00f6dien<\/strong> und <strong>Kassenschm\u00e4hdien<\/strong>. Diese <strong>Wortsch\u00f6pfung<\/strong> von <a href=\"http:\/\/www.uwe-dick.de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Uwe Dick<\/strong><\/a> aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur <strong>die Medienindustrie<\/strong> auf den Punkt, <strong>sie verdeutlicht<\/strong> geradezu das gesamte <strong>Unwesen unserer Zivilisation<\/strong>. Doch <strong>den Nachthasen ist kein roter Faden zu d\u00fcnn<\/strong>, um aus ihm nicht doch noch ein mutmachendes <strong>Hurra aufs \u00dcberleben<\/strong> zu destillieren: <strong>\u201cSexuell benutzerdefiniert\u201d<\/strong> im Gegensatz zu den <strong>\u201cempfohlenen Einstellungen\u201d<\/strong> der ohnehin unklaren Anbieter, es k\u00f6nnte so einfach sein, <strong>wenn man sich nur lie\u00dfe<\/strong>. Auf jeden Fall <strong>empfehlen wir uns<\/strong>.<\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-6567 size-medium\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-300x200.jpg\" alt=\"velvet oscar wilde\" width=\"300\" height=\"200\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-300x200.jpg 300w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-768x512.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-1024x682.jpg 1024w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-450x300.jpg 450w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Oder <a href=\"https:\/\/de.wikipedia.org\/wiki\/Oscar_Wilde\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Oscar Wilde<\/strong><\/a>, den verwegenen Vork\u00e4mpfer f\u00fcr das <strong>Menschenrecht auf sexuelle Selbstbestimmung<\/strong> im viktorianisch verklemmten England. Der ging f\u00fcr sein stures Beharren auf <strong>gleichgeschlechtlicher Liebe als einer m\u00f6glichen Lebensform<\/strong> nicht nur ins Gef\u00e4ngnis, sondern an den Folgen dieser Unmenschlichkeit zudem auch <strong>tats\u00e4chlich<\/strong> zugrunde. Was nicht verhindern konnte, dass er <strong>seine Mit- und Nachwelt<\/strong> (also uns) mit einer <a href=\"https:\/\/www.aphorismen.de\/suche?f_autor=4081_Oscar+Wilde\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>\u00dcberf\u00fclle an zeitlos klugen Zitaten<\/strong><\/a> beschenkte. Viele davon finden sich <strong>im Script von Velvet Goldmine<\/strong> wieder, als einer von <strong>vielen roten F\u00e4den<\/strong>, die diesen Film so wunderbar <strong>unbl\u00f6d und wertvoll<\/strong> machen. Und ihn <strong>\u00fcber die Jahre<\/strong> zu einem Kultfilm, vor allem <strong>f\u00fcr ein jugendliches Publikum<\/strong>, werden lie\u00dfen, wiewohl er<strong> in den Kinos<\/strong> gefloppt war. <em><strong>\u201cOh mein Gott, Hollywood verhungert, sammelt Steckr\u00fcben!\u201d<\/strong><\/em> Die statistische <strong>Bewertung der Verkaufserl\u00f6se<\/strong> zeigt nur, wie <strong>unma\u00dfgeblich<\/strong> <strong>kommerzielle \u00dcberlegungen<\/strong> f\u00fcr den <strong>pers\u00f6nlichen Wert eines Kunstwerks<\/strong> sind. Und wie <strong>unerheblich die Mehrheitsmeinung<\/strong> im Hinblick auf <strong>individuelles Ber\u00fchrtwerden<\/strong> ist. <strong>Massengeschmack<\/strong> kann niemals <strong>Ma\u00dfstab f\u00fcr die eigene Wahrhaftigkeit<\/strong> sein.<\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-goldmine.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-6574 size-medium\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-goldmine-200x300.jpg\" alt=\"velvet goldmine\" width=\"200\" height=\"300\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-goldmine-200x300.jpg 200w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-goldmine-768x1152.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-goldmine-683x1024.jpg 683w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-goldmine.jpg 1000w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a>So beginnt <strong>Velvet Goldmine<\/strong> folgerichtig mit <strong>Oscar Wildes Kindheit<\/strong> (als Vorgeschichte), um sich dann jener <a href=\"https:\/\/de.wikipedia.org\/wiki\/Glam_Rock\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>kurzen \u00c4ra des Glam Rock der 70er Jahre<\/strong><\/a> hinzugeben, als<strong> erstmals im Pop<\/strong> musizierende M\u00e4nner <strong>sexuell ambivalent<\/strong> auftraten und \u00f6ffentlich <a href=\"https:\/\/www.youtube.com\/watch?v=gbvRNvUKhc4\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>mit eventueller Bisexualit\u00e4t<\/strong><\/a> spielten. Der \u00fcberaus vielschichtige, teils <strong>symbolistisch<\/strong> und <strong>surreal in Stimmungsbildern<\/strong> gestaltete Film fokussiert auf <strong>die beiden Rockstars Brian Slade alias Maxwell Demon<\/strong> (dessen Rolle <strong>David Bowie alias Ziggy Stardust<\/strong> nachempfunden ist) sowie <strong>Curt Wild<\/strong> (dessen Rolle unter anderem von <strong>Iggy Pop<\/strong> und <strong>Lou Reed<\/strong> inspiriert wurde) und erz\u00e4hlt von deren <strong>Begegnung<\/strong>, <strong>Verliebtheit und schlussendlichem Verfall<\/strong>. Das allein w\u00e4re schon genug an <strong>Opulenz<\/strong>, <strong>Dimensionalit\u00e4t<\/strong> und <strong>Vertracktheit<\/strong>, doch da ist auch noch <strong>die Rahmenhandlung des Erz\u00e4hlers Arthur Stuart<\/strong>, eines <strong>Musikjournalisten<\/strong>, dessen <strong>investigative Recherchen<\/strong> mittels <strong>diverser R\u00fcckblenden<\/strong> in die <strong>\u00fcberbordende Erz\u00e4hlung<\/strong> hinein verwoben sind. Insgesamt also <strong>ein Spielfilm<\/strong>, der keineswegs durch <strong>n\u00fcchternes Frontalbewusstsein begriffen<\/strong>, sondern <strong>vielmehr vermittels des entgrenzten Gef\u00fchlsverstands erlebt<\/strong> <strong>werden will<\/strong>. Und vor allem nicht <strong>\u201cinterpretiert\u201d<\/strong>.<\/p>\n<p><a href=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-quote.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-6582 size-medium\" src=\"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-quote-300x195.jpg\" alt=\"velvet oscar wilde quote\" width=\"300\" height=\"195\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-quote-300x195.jpg 300w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-quote-768x499.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-quote-1024x666.jpg 1024w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-quote-462x300.jpg 462w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-quote.jpg 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Was mit Sicherheit auch auf die <a href=\"http:\/\/michaelstipe.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Homepage von Michael Stipe<\/strong><\/a> zutrifft, der <strong>Velvet Goldmine<\/strong> als <strong>Herzensanliegen<\/strong> produziert hat. <strong>Bitte halten sie mich fest!<\/strong> Oder sonstwas. <strong>Wie<\/strong> dem auch <strong>immer<\/strong> <strong>nicht<\/strong> sei, <strong>wir zwei<\/strong> gewinnen dieser unendlich sch\u00f6nen Herausforderung aller Sinne <strong>naturgem\u00e4\u00df einiges<\/strong> an <strong>Gef\u00fchlen und Bez\u00fcgen<\/strong> ab. Darob werden wir hiernachts schwelgen k\u00f6nnen, <strong>dem Erz\u00e4hlstrang<\/strong> sowie <a href=\"https:\/\/www.youtube.com\/watch?v=xOXQSgZNq0A&amp;index=1&amp;list=RDxOXQSgZNq0A\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>dem Soundtrack<\/strong><\/a> dieses <strong>musikalischen Ausnahmefilms<\/strong> folgend. Sontstwo erschienene<strong> Rezensionen<\/strong> halten wir allesamt f\u00fcr <strong>hochgradig verschn\u00f6selt<\/strong> und daher <strong>nichtssagend<\/strong>. Statt dass etwa <strong>die Ergriffenen<\/strong> schrieben, denen <em><strong>\u201cdas etwas gibt\u201d<\/strong><\/em>, verzapfen da irgendwelche <strong>\u201cZust\u00e4ndige\u201d<\/strong> ihre Ma\u00dfstabsmeinung, die <strong>kein authentisches Erleben<\/strong> wiederspiegelt, sondern stattdessen <strong>das all\u00fcbliche Gesums<\/strong> aus dem <strong>Eintupf der sachzw\u00e4nglichen Durchschnitter<\/strong>. Was <strong>sexuell neugierige Welpentiere<\/strong> interessiern darf und was nicht, das wird von <strong>abgeschmackt normifizierten Pudernudeln<\/strong> festgeschrieben und in den <strong>\u201cneuen\u201d Untenhaltungsmedien<\/strong> reichweitigst verbetoniert. Es hat sich nichts ge\u00e4ndert: <strong>Was \u201cnormal\u201d ist<\/strong>, entscheiden <strong>die Angepassten<\/strong>. Und <strong>die spinnen mit Sicherheit!<\/strong><\/p>\n<p><em><strong>\u201cGleich am Tag nach meinem Tod setz ich mich hin und schreib meine Memoiren. Davor bin ich viel zu sehr mit meinem Leben besch\u00e4ftigt.\u201d<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni &#8211; Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur &#8211; und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4015,77,71],"tags":[4026,7593,4045,4052,4029,4016,83,4040],"class_list":["post-6562","post","type-post","status-publish","format-standard","hentry","category-in-produktion","category-projekt","category-sendung","tag-ambivalent","tag-aufbruch","tag-be-greifen","tag-empowerment","tag-experiment","tag-inbetween","tag-inteam","tag-selbsterkenntnis"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung von Uwe Dick aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"artarium\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Velvet Goldmine - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta property=\"og:description\" content=\"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung von Uwe Dick aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-06-05T20:44:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-04-09T13:35:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Velvet Goldmine - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung von Uwe Dick aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#blogposting\",\"name\":\"Velvet Goldmine - Nachtfahrt Perlentaucher\",\"headline\":\"Velvet Goldmine\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/files\\\/2017\\\/06\\\/velvet-oscar-wilde-300x200.jpg\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#articleImage\"},\"datePublished\":\"2017-06-05T20:44:28+00:00\",\"dateModified\":\"2018-04-09T13:35:30+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#webpage\"},\"articleSection\":\"In Produktion, Projekt, Sendung, ambivalent, aufbruch, be-greifen, empowerment, experiment, inbetween, inteam, selbsterkenntnis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/sendung\\\/#listItem\",\"name\":\"Sendung\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/sendung\\\/#listItem\",\"position\":2,\"name\":\"Sendung\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/sendung\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#listItem\",\"name\":\"Velvet Goldmine\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#listItem\",\"position\":3,\"name\":\"Velvet Goldmine\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/sendung\\\/#listItem\",\"name\":\"Sendung\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/\",\"name\":\"artarium\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"artarium\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/\",\"name\":\"Velvet Goldmine - Nachtfahrt Perlentaucher\",\"description\":\"> Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\\u00f6dien, Quassel\\u00f6dien und Kassenschm\\u00e4hdien. Diese Wortsch\\u00f6pfung von Uwe Dick aus den \\u201cgoldenen\\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/sendung\\\/velvet-goldmine\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"datePublished\":\"2017-06-05T20:44:28+00:00\",\"dateModified\":\"2018-04-09T13:35:30+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Velvet Goldmine - Nachtfahrt Perlentaucher","description":"> Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung von Uwe Dick aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf","canonical_url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#blogposting","name":"Velvet Goldmine - Nachtfahrt Perlentaucher","headline":"Velvet Goldmine","author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2017\/06\/velvet-oscar-wilde-300x200.jpg","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#articleImage"},"datePublished":"2017-06-05T20:44:28+00:00","dateModified":"2018-04-09T13:35:30+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#webpage"},"articleSection":"In Produktion, Projekt, Sendung, ambivalent, aufbruch, be-greifen, empowerment, experiment, inbetween, inteam, selbsterkenntnis"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","position":1,"name":"Home","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/sendung\/#listItem","name":"Sendung"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/sendung\/#listItem","position":2,"name":"Sendung","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/sendung\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#listItem","name":"Velvet Goldmine"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#listItem","position":3,"name":"Velvet Goldmine","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/sendung\/#listItem","name":"Sendung"}}]},{"@type":"Organization","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/","name":"artarium","image":{"@type":"ImageObject","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=mm&r=pg","width":96,"height":96,"caption":"artarium"}},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#webpage","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/","name":"Velvet Goldmine - Nachtfahrt Perlentaucher","description":"> Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung von Uwe Dick aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"creator":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"datePublished":"2017-06-05T20:44:28+00:00","dateModified":"2018-04-09T13:35:30+00:00"},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","og:type":"article","og:title":"Velvet Goldmine - Nachtfahrt Perlentaucher","og:description":"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung von Uwe Dick aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf","og:url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/","article:published_time":"2017-06-05T20:44:28+00:00","article:modified_time":"2018-04-09T13:35:30+00:00","twitter:card":"summary","twitter:title":"Velvet Goldmine - Nachtfahrt Perlentaucher","twitter:description":"&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 9. Juni - Auf den Spuren des Kultfilms Velvet Goldmine w\u00fcrdigen wir die sexuelle Ambivalenz in der Popkultur - und w\u00fcrgen am heteronormativen Durchschnitt einer bumsdummen Gesellschaft aus Massenbl\u00f6dien, Quassel\u00f6dien und Kassenschm\u00e4hdien. Diese Wortsch\u00f6pfung von Uwe Dick aus den \u201cgoldenen\u201d 70er Jahren bringt ja nicht nur die Medienindustrie auf"},"aioseo_meta_data":{"post_id":"6562","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-09 20:43:39","updated":"2025-06-04 02:43:58","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/sendung\/\" title=\"Sendung\">Sendung<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tVelvet Goldmine\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt"},{"label":"Sendung","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/sendung\/"},{"label":"Velvet Goldmine","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/sendung\/velvet-goldmine\/"}],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/6562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/comments?post=6562"}],"version-history":[{"count":39,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/6562\/revisions"}],"predecessor-version":[{"id":6950,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/6562\/revisions\/6950"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/media?parent=6562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/categories?post=6562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/tags?post=6562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}