{"id":9775,"date":"2025-03-11T19:31:01","date_gmt":"2025-03-11T19:31:01","guid":{"rendered":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/?p=9775"},"modified":"2025-03-15T14:31:19","modified_gmt":"2025-03-15T14:31:19","slug":"triptychon-zur-traurigkeit","status":"publish","type":"post","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/","title":{"rendered":"Triptychon zur Traurigkeit"},"content":{"rendered":"<p><strong>&gt; Sendung: <a href=\"https:\/\/cba.media\/701551\" target=\"_blank\" rel=\"noopener\">Perlentaucher Nachtfahrt vom Freitag, 14. M\u00e4rz<\/a><\/strong> &#8211; <em>\u201cUnd, wie f\u00fchlst du dich jetzt nach diesen \u00dcbungen?\u201d<\/em>, fragt <a href=\"https:\/\/www.youtube.com\/watch?v=L1VXoBXFq1w\"><strong>der freundliche Arzt<\/strong><\/a> aus dem Internet. Mir f\u00e4llt spontan <strong>eine Antwort<\/strong> heraus: <em>\u201cIch habe <strong>Angst<\/strong>. <strong>Angst<\/strong> vor meinen <strong>Schmerzen<\/strong>. Und <strong>Angst<\/strong> vor meiner <strong>Traurigkeit<\/strong>.\u201d<\/em> Da schau her. Das heutige <strong>Sendungsthema<\/strong> ist eines der <strong>schwierigsten<\/strong> und <strong>unzug\u00e4nglichsten<\/strong> von all den <a href=\"https:\/\/www.die-inkognito-philosophin.de\/blog\/traurigkeit-trauer\" target=\"_blank\" rel=\"noopener\"><strong>Gef\u00fchlskonglomeraten<\/strong>,<\/a> die wir bislang in unseren <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/?s=traurig&amp;submit=Suchen\" target=\"_blank\" rel=\"noopener\"><strong>Perlentauchereien<\/strong><\/a> untersucht haben. <strong>Eine Herausforderung<\/strong>, die sich aber auch <strong>zunehmend aufdr\u00e4ngt<\/strong>. Seit einiger Zeit kommen mir n\u00e4mlich vermehrt Menschen unter, die eine geradezu <strong>traurigkeitsvermeidende \u00dcberlebensstrategie<\/strong> zu verfolgen scheinen. Die also <strong>alles<\/strong>, was sie in diesen Gef\u00fchlszustand versetzen k\u00f6nnte, <strong>von vorn herein von sich fernhalten<\/strong>. Die vielleicht, <strong>so wie ich<\/strong>, <strong>Angst<\/strong> davor haben<strong>?<\/strong><\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-9777\" src=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1-300x225.jpg\" alt=\"Triptychon zur Traurigkeit 1\" width=\"300\" height=\"225\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1-300x225.jpg 300w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1-1024x768.jpg 1024w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1-768x576.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1-1536x1152.jpg 1536w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1-2048x1536.jpg 2048w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1-400x300.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><strong>Traurigkeit ist wie ein Schleier<\/strong>. Ich hab mal versucht, mir etwas zugleich so <strong>ungreifbares<\/strong> wie auch <strong>massives<\/strong> vorzustellen wie <strong>\u201cbleiernen Nebel\u201d<\/strong> (der sich \u00fcber die Seele legt oder so \u00e4hnlich). Ein sich beinah unmerklich ausbreitendes <strong>Gespinst<\/strong>, das <strong>in uns eindringt<\/strong> und <strong>uns von allen Seiten umgibt<\/strong>, <strong>sich in weiterer Folge zu einer immer undurchdringlicheren Barriere verdichtet<\/strong>, <strong>die uns von dort<\/strong>,<strong> wo wir unser Lebendigsein<\/strong> <strong>sp\u00fcren w\u00fcrden<\/strong>, <strong>regelrecht abtrennt<\/strong>. Da kommen mir <strong>Bilder von Betonbunkern<\/strong> und <strong>Kernkraftwerken<\/strong> in den Sinn, von eingesperrtem Lebenwollen, das bei jedem Versuch, nach au\u00dfen durchzudringen, <strong>an seinem Gefangensein scheitert<\/strong>. Da steht <strong>eine Wand<\/strong> <strong>zwischen mir und der Welt<\/strong>, <strong>zwischen ich und du<\/strong>, <strong>zwischen einem traurigen Kind und der unendlichen Landschaft seiner Tr\u00e4ume<\/strong>. <strong>Das ist wie damals<\/strong>, <strong>als <em>du<\/em> mich<\/strong> <strong>nicht verstanden<\/strong> &#8211; <strong>nicht gesehen<\/strong>, <strong>nicht gesp\u00fcrt<\/strong>, <strong>nicht wahrgenommen<\/strong> &#8211; <strong>hast<\/strong>. Es f\u00fchlt sich heute noch so an, wenn ich <em>entt\u00e4uscht<\/em> bin. Oder ist es <strong>\u201cnur\u201d<\/strong> <a href=\"https:\/\/www.die-inkognito-philosophin.de\/blog\/entwicklungstrauma\" target=\"_blank\" rel=\"noopener\"><strong>ein Flashback?<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-9782\" src=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2-300x223.jpg\" alt=\"Triptychon zur Traurigkeit 2\" width=\"300\" height=\"223\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2-300x223.jpg 300w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2-1024x763.jpg 1024w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2-768x572.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2-1536x1144.jpg 1536w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2-2048x1525.jpg 2048w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-2-403x300.jpg 403w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><strong>Traurigkeit erz\u00e4hlt Geschichten<\/strong>. Nat\u00fcrlich <strong>nicht gerade dann<\/strong>, wenn wir in ihr <strong>versinken<\/strong>. Doch sobald wir uns wieder <strong>lebendig<\/strong> f\u00fchlen, k\u00f6nnen wir <strong>ganz ohne Zwang zuh\u00f6ren<\/strong>. Als ich gestern in den ziemlich genialen Dokumentarfilm <a href=\"https:\/\/www.3sat.de\/film\/dokumentarfilmzeit\/was-tun-100.html\" target=\"_blank\" rel=\"noopener\"><strong>\u201cWas tun\u201d<\/strong><\/a> geraten bin, hat sich mir so eine Geschichte geradezu <strong>elementar ereignet<\/strong>, dass ich <strong>wieder ganz neu neugierig<\/strong> auf das <strong>unendliche Land<\/strong> hinter meiner <strong>Traurigkeit<\/strong> geworden bin. <a href=\"https:\/\/www.was-tun-film.de\/\" target=\"_blank\" rel=\"noopener\"><strong>Der Film<\/strong><\/a> behandelt die <strong>Situation von Sexarbeiterinnen<\/strong> in den <strong>Bordellen von Bangladesh<\/strong>, an und f\u00fcr sich <strong>ein zutiefst trauriges Thema<\/strong>, und mir fiel auf, dass ich dabei <strong>nichts von dem<\/strong> empfand, <strong>was ich<\/strong> sonst <strong>als das traurige Gef\u00fchl<\/strong> bei mir <strong>kenne<\/strong>. Ich wunderte mich dar\u00fcber &#8211; und <strong>ging innerlich auf die Suche<\/strong>. Kurz darauf begegnete mir <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Redoy.jpg\" target=\"_blank\" rel=\"noopener\"><strong>Redoy<\/strong>,<\/a> den Regisseur <a href=\"https:\/\/de.wikipedia.org\/wiki\/Michael_Kranz\" target=\"_blank\" rel=\"noopener\"><strong>Michael Kranz<\/strong><\/a> als <em>\u201cmeinen besten Freund\u201d<\/em> und <em>\u201cmein bengalisches Herz\u201d<\/em> bezeichnet &#8211; <strong>und ich erkannte mich selbst<\/strong>. In einer heftigen Ersch\u00fctterung von <strong>zugleich Weinen und Lachen<\/strong> endlich wieder <strong>ganz<\/strong>.<\/p>\n<p><a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-9805\" src=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3-300x225.jpg\" alt=\"Triptychon zur Traurigkeit 3\" width=\"300\" height=\"225\" srcset=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3-300x225.jpg 300w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3-1024x768.jpg 1024w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3-768x576.jpg 768w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3-1536x1152.jpg 1536w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3-2048x1536.jpg 2048w, https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-3-400x300.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><strong>Traurigkeit kann eine Spur sein<\/strong>. <strong>Dorthin<\/strong>, wo sich <strong>R\u00e4ume auftun<\/strong> und <strong>neue Wege er\u00f6ffnen<\/strong>. Neu insofern, als sie vielleicht <strong>schon lang nicht mehr betreten worden<\/strong> sind. Weil wir gelernt haben, sie zu <strong>vermeiden<\/strong>. <strong>Weil wir \u00fcberlebt haben<\/strong> (und das ist <strong>definitiv<\/strong> ein Grund zum Feiern). Nichtsdestoweniger sind es <strong><em>unsere<\/em> Wege<\/strong>, auf denen wir <strong>als gl\u00fcckliche Kinder im Sonnenschein unserer Neugier herumtrubeln<\/strong> und <strong>dabei auch die Abenteuer des Waldes und der Finsternis entdecken und bestehen<\/strong>. Es kommt nur darauf an (und zwar schei\u00dfegal wie alt wir sind), <strong>neugierig zu bleiben<\/strong> und sich schon auch mal <strong>\u00fcberraschen zu lassen<\/strong>. <strong>Oder wollt ihr die totale Langeweile?<\/strong> Den schleichenden Erstickungstod <strong>durch immer dieselbe Reiz-Reaktions-Routine? <\/strong>Den Schleier der Traurigkeit <strong>anheben<\/strong>, die Geschichte dahinter <strong>verstehen wollen<\/strong>, der Spur ihres R\u00e4tsels <strong>folgen<\/strong> und <strong>das Geheimnis ergr\u00fcnden<\/strong>. <strong>Mit sich selbst auf Du<\/strong> &#8211; das ist <strong>ein guter Anfang<\/strong> f\u00fcr das <strong>Frage-und-Antwort-Spiel<\/strong> mit der <strong>Welt da drau\u00dfen<\/strong>.<\/p>\n<p><strong>Lust auf mehr? Einfach mittauchen und <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2021\/08\/Station-ID-Thomas-Oberender.mp3\" target=\"_blank\" rel=\"noopener\">gut zu h\u00f6ren.<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt; Sendung: Perlentaucher Nachtfahrt vom Freitag, 14. M\u00e4rz &#8211; \u201cUnd, wie f\u00fchlst du dich jetzt nach diesen \u00dcbungen?\u201d, fragt der freundliche Arzt aus dem Internet. Mir f\u00e4llt spontan eine Antwort heraus: \u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst &hellip; <a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4015,85,1,77,71],"tags":[4026,7594,4035,4016,4044,4041,4040,4043,22584,22585,4027,22586],"class_list":["post-9775","post","type-post","status-publish","format-standard","hentry","category-in-produktion","category-konzept","category-uncategorized","category-projekt","category-sendung","tag-ambivalent","tag-auf-der-suche","tag-das-leben-lebt","tag-inbetween","tag-magische-phantasie","tag-scheinwelt-entzaubern","tag-selbsterkenntnis","tag-tot-leben","tag-vergangenheit","tag-verlust","tag-verwandeln","tag-verwegen"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"artarium\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta property=\"og:description\" content=\"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-03-11T19:31:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-15T14:31:19+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#blogposting\",\"name\":\"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher\",\"headline\":\"Triptychon zur Traurigkeit\",\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/files\\\/2025\\\/03\\\/Triptychon-zur-Traurigkeit-1.jpg\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#articleImage\",\"width\":2560,\"height\":1920,\"caption\":\"Triptychon zur Traurigkeit 1\"},\"datePublished\":\"2025-03-11T19:31:01+00:00\",\"dateModified\":\"2025-03-15T14:31:19+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#webpage\"},\"articleSection\":\"In Produktion, Konzept, Passt in keine Schachtel, Projekt, Sendung, ambivalent, auf der suche, das leben lebt, inbetween, magische phantasie, scheinwelt entzaubern, selbsterkenntnis, tot.leben, vergangenheit, verlust, verwandeln, verwegen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Passt in keine Schachtel\",\"item\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#listItem\",\"name\":\"Triptychon zur Traurigkeit\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#listItem\",\"position\":3,\"name\":\"Triptychon zur Traurigkeit\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Passt in keine Schachtel\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/\",\"name\":\"artarium\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=mm&r=pg\",\"width\":96,\"height\":96,\"caption\":\"artarium\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#webpage\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/\",\"name\":\"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher\",\"description\":\"\\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/uncategorized\\\/triptychon-zur-traurigkeit\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/author\\\/artarium\\\/#author\"},\"datePublished\":\"2025-03-11T19:31:01+00:00\",\"dateModified\":\"2025-03-15T14:31:19+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#website\",\"url\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/\",\"name\":\"Nachtfahrt Perlentaucher\",\"description\":\"Musikliterarische Gef\\u00fchlsweltreise mit tiefgr\\u00fcndigen Themen\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.radiofabrik.at\\\/nachtfahrt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher","description":"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...","canonical_url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#blogposting","name":"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher","headline":"Triptychon zur Traurigkeit","author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#articleImage","width":2560,"height":1920,"caption":"Triptychon zur Traurigkeit 1"},"datePublished":"2025-03-11T19:31:01+00:00","dateModified":"2025-03-15T14:31:19+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#webpage"},"isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#webpage"},"articleSection":"In Produktion, Konzept, Passt in keine Schachtel, Projekt, Sendung, ambivalent, auf der suche, das leben lebt, inbetween, magische phantasie, scheinwelt entzaubern, selbsterkenntnis, tot.leben, vergangenheit, verlust, verwandeln, verwegen"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","position":1,"name":"Home","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","position":2,"name":"Passt in keine Schachtel","item":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#listItem","name":"Triptychon zur Traurigkeit"},"previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#listItem","position":3,"name":"Triptychon zur Traurigkeit","previousItem":{"@type":"ListItem","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/#listItem","name":"Passt in keine Schachtel"}}]},{"@type":"Organization","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/"},{"@type":"Person","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/","name":"artarium","image":{"@type":"ImageObject","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6db59e27fd0b23fecbe8b68486ed6b638848fb8c1483d1931a1efe842d93a722?s=96&d=mm&r=pg","width":96,"height":96,"caption":"artarium"}},{"@type":"WebPage","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#webpage","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/","name":"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher","description":"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website"},"breadcrumb":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/#breadcrumblist"},"author":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"creator":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/author\/artarium\/#author"},"datePublished":"2025-03-11T19:31:01+00:00","dateModified":"2025-03-15T14:31:19+00:00"},{"@type":"WebSite","@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#website","url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/","name":"Nachtfahrt Perlentaucher","description":"Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","inLanguage":"de-DE","publisher":{"@id":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Nachtfahrt Perlentaucher - Musikliterarische Gef\u00fchlsweltreise mit tiefgr\u00fcndigen Themen","og:type":"article","og:title":"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher","og:description":"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...","og:url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/","og:image":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg","og:image:secure_url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg","og:image:width":"2560","og:image:height":"1920","article:published_time":"2025-03-11T19:31:01+00:00","article:modified_time":"2025-03-15T14:31:19+00:00","twitter:card":"summary","twitter:title":"Triptychon zur Traurigkeit - Nachtfahrt Perlentaucher","twitter:description":"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...","twitter:image":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg"},"aioseo_meta_data":{"post_id":"9775","title":null,"description":"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...","keywords":null,"keyphrases":{"focus":{"keyphrase":"Traurigkeit","score":100,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":"\u201cIch habe Angst. Angst vor meinen Schmerzen. Und Angst vor meiner Traurigkeit.\u201d Da schau her. Das heutige Sendungsthema ist eines der schwierigsten ...","og_object_type":"default","og_image_type":"content","og_image_url":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/files\/2025\/03\/Triptychon-zur-Traurigkeit-1.jpg","og_image_width":"2560","og_image_height":"1920","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-03-10 12:28:39","updated":"2025-06-04 02:53:39","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/\" title=\"Passt in keine Schachtel\">Passt in keine Schachtel<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTriptychon zur Traurigkeit\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt"},{"label":"Passt in keine Schachtel","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/category\/uncategorized\/"},{"label":"Triptychon zur Traurigkeit","link":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/uncategorized\/triptychon-zur-traurigkeit\/"}],"_links":{"self":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/9775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/comments?post=9775"}],"version-history":[{"count":45,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/9775\/revisions"}],"predecessor-version":[{"id":9824,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/posts\/9775\/revisions\/9824"}],"wp:attachment":[{"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/media?parent=9775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/categories?post=9775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.radiofabrik.at\/nachtfahrt\/wp-json\/wp\/v2\/tags?post=9775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}